{"id":30851,"date":"2022-10-19T00:00:00","date_gmt":"2022-10-18T22:00:00","guid":{"rendered":"https:\/\/new.barcelonatribuna.com\/debat_amics_del_pais_con_jaume_padros_y_guillem_lopez_casasnovas\/"},"modified":"2025-12-09T18:22:25","modified_gmt":"2025-12-09T17:22:25","slug":"debat_amics_del_pais_con_jaume_padros_y_guillem_lopez_casasnovas","status":"publish","type":"post","link":"https:\/\/www.amicsdelpais.com\/es\/debat_amics_del_pais_con_jaume_padros_y_guillem_lopez_casasnovas\/","title":{"rendered":"Debat Amics del Pa\u00eds con Jaume Padr\u00f3s y Guillem L\u00f3pez Casasnovas"},"content":{"rendered":"         <p class=\"link_ariadna\">             <a href=\"https:\/\/www.amicsdelpais.com\/es\/agenda\">Agenda<\/a>         <\/p>                   <h1 class=\"wp-block-post-title\">Debat Amics del Pa\u00eds con Jaume Padr\u00f3s y Guillem L\u00f3pez Casasnovas<\/h1>          <style>.kb-row-layout-id15198_fd4370-d2 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id15198_fd4370-d2 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id15198_fd4370-d2 > .kt-row-column-wrap{column-gap:40px;row-gap:var(--global-kb-gap-md, 2rem);padding-top:0px;padding-bottom:24px;grid-template-columns:minmax(0, calc(70% - ((40px * 1 )\/2)))minmax(0, calc(30% - ((40px * 1 )\/2)));}.kb-row-layout-id15198_fd4370-d2 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id15198_fd4370-d2 > .kt-row-column-wrap{grid-template-columns:minmax(0, 2fr) minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id15198_fd4370-d2 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id15198_fd4370-d2 alignnone header_article_agenda wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-left-golden kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">             <style>.kadence-column15198_b1d053-1d > .kt-inside-inner-col,.kadence-column15198_b1d053-1d > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column15198_b1d053-1d > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column15198_b1d053-1d > .kt-inside-inner-col{flex-direction:column;}.kadence-column15198_b1d053-1d > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column15198_b1d053-1d > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column15198_b1d053-1d{position:relative;}@media all and (max-width: 1024px){.kadence-column15198_b1d053-1d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column15198_b1d053-1d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>             <div class=\"wp-block-kadence-column kadence-column15198_b1d053-1d\">                 <div class=\"kt-inside-inner-col\">                     <figure class=\"wp-block-post-featured-image\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/www.amicsdelpais.com\/wp-content\/uploads\/2025\/09\/1867_cb_az8q7410-2-scaled.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"\" style=\"object-fit:cover;\" srcset=\"https:\/\/www.amicsdelpais.com\/wp-content\/uploads\/2025\/09\/1867_cb_az8q7410-2-scaled.jpg 2560w, https:\/\/www.amicsdelpais.com\/wp-content\/uploads\/2025\/09\/1867_cb_az8q7410-2-300x200.jpg 300w, https:\/\/www.amicsdelpais.com\/wp-content\/uploads\/2025\/09\/1867_cb_az8q7410-2-1024x683.jpg 1024w, https:\/\/www.amicsdelpais.com\/wp-content\/uploads\/2025\/09\/1867_cb_az8q7410-2-768x512.jpg 768w, https:\/\/www.amicsdelpais.com\/wp-content\/uploads\/2025\/09\/1867_cb_az8q7410-2-1536x1024.jpg 1536w, https:\/\/www.amicsdelpais.com\/wp-content\/uploads\/2025\/09\/1867_cb_az8q7410-2-2048x1365.jpg 2048w, https:\/\/www.amicsdelpais.com\/wp-content\/uploads\/2025\/09\/1867_cb_az8q7410-2-1200x800.jpg 1200w, https:\/\/www.amicsdelpais.com\/wp-content\/uploads\/2025\/09\/1867_cb_az8q7410-2-600x400.jpg 600w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/figure>                 <\/div>             <\/div>                           <style>.kadence-column15494_3829e6-92 > .kt-inside-inner-col,.kadence-column15494_3829e6-92 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column15494_3829e6-92 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column15494_3829e6-92 > .kt-inside-inner-col{flex-direction:column;}.kadence-column15494_3829e6-92 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column15494_3829e6-92 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column15494_3829e6-92{position:relative;}@media all and (max-width: 1024px){.kadence-column15494_3829e6-92 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column15494_3829e6-92 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>             <div class=\"wp-block-kadence-column kadence-column14090_3b8e58-5d\">                 <div class=\"kt-inside-inner-col\">                      <h4 class=\"wp-block-heading\">     <a href=\"\/es\/comision-salud\">Comisi\u00f3n Salud<\/a> <\/h4>                           <p class=\"date_event\" style=\"font-size:45px\">19-10-2022<\/p>                       <style>.kadence-column14090_70773d-d2 > .kt-inside-inner-col{padding-top:20px;padding-right:20px;padding-bottom:20px;padding-left:20px;}.kadence-column14090_70773d-d2 > .kt-inside-inner-col,.kadence-column14090_70773d-d2 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column14090_70773d-d2 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column14090_70773d-d2 > .kt-inside-inner-col{flex-direction:column;}.kadence-column14090_70773d-d2 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column14090_70773d-d2 > .kt-inside-inner-col{background-color:var(--global-palette1, #3182CE);}.kadence-column14090_70773d-d2 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column14090_70773d-d2{position:relative;}.kadence-column14090_70773d-d2, .kt-inside-inner-col > .kadence-column14090_70773d-d2:not(.specificity){margin-bottom:60px;}@media all and (max-width: 1024px){.kadence-column14090_70773d-d2 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column14090_70773d-d2 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>                     <div class=\"wp-block-kadence-column kadence-column14090_70773d-d2\">                         <div class=\"kt-inside-inner-col\">                          <style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box14090_ef2130-11 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box14090_ef2130-11 .kt-blocks-info-box-link-wrap{border-top:0px solid var(u002du002dglobal-palette7, #eeeeee);border-right:0px solid var(u002du002dglobal-palette7, #eeeeee);border-bottom:1px solid #979797;border-left:0px solid var(u002du002dglobal-palette7, #eeeeee);border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:var(--global-palette1, #3182CE);padding-top:0px;padding-right:0px;padding-bottom:10px;padding-left:0px;margin-bottom:10px;}.kt-info-box14090_ef2130-11 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box14090_ef2130-11 .kt-info-svg-icon-flip, .kt-info-box14090_ef2130-11 .kt-blocks-info-box-number{font-size:20px;}.kt-info-box14090_ef2130-11 .kt-blocks-info-box-media{color:var(--global-palette4, #2D3748);border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:3px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:7px;margin-bottom:0px;margin-left:0px;}.kt-info-box14090_ef2130-11 .kt-infobox-textcontent h6.kt-blocks-info-box-title{color:var(--global-palette4, #2D3748);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box14090_ef2130-11 .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette4, #2D3748);}.kt-info-box14090_ef2130-11 .kt-blocks-info-box-learnmore{background:transparent;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}@media all and (max-width: 1024px){.kt-info-box14090_ef2130-11 .kt-blocks-info-box-link-wrap{border-top:0px solid var(u002du002dglobal-palette7, #eeeeee);border-right:0px solid var(u002du002dglobal-palette7, #eeeeee);border-bottom:1px solid #979797;border-left:0px solid var(u002du002dglobal-palette7, #eeeeee);}}@media all and (max-width: 767px){.kt-info-box14090_ef2130-11 .kt-blocks-info-box-link-wrap{border-top:0px solid var(u002du002dglobal-palette7, #eeeeee);border-right:0px solid var(u002du002dglobal-palette7, #eeeeee);border-bottom:1px solid #979797;border-left:0px solid var(u002du002dglobal-palette7, #eeeeee);}}<\/style>                             <div class=\"wp-block-kadence-infobox kt-info-box14090_ef2130-11 info_block_01\">                             <span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-left kt-info-halign-left kb-info-box-vertical-media-align-top\">                                 <div class=\"kt-blocks-info-box-media-container\">                                 <div class=\"kt-blocks-info-box-media kt-info-media-animate-none\">                                     <div class=\"kadence-info-box-icon-container kt-info-icon-animate-none\">                                     <div class=\"kadence-info-box-icon-inner-container\">                                         <span class=\"kb-svg-icon-wrap kb-svg-icon-fe_clock kt-info-svg-icon\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  role=\"img\"><title>Hora<\/title><circle cx=\"12\" cy=\"12\" r=\"10\"\/><polyline points=\"12 6 12 12 16 14\"\/><\/svg><\/span>                                     <\/div>                                     <\/div>                                 <\/div>                                 <\/div>                                 <div class=\"kt-infobox-textcontent\">                                 <h6 class=\"kt-blocks-info-box-title\">Hora<\/h6>                                 <p class=\"kt-blocks-info-box-text\">19:00<\/p>                                 <\/div>                             <\/span>                             <\/div>                                                   <style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box14090_2b0351-ed .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box14090_2b0351-ed .kt-blocks-info-box-link-wrap{border-top:0px solid var(u002du002dglobal-palette7, #eeeeee);border-right:0px solid var(u002du002dglobal-palette7, #eeeeee);border-bottom:0px solid #979797;border-left:0px solid var(u002du002dglobal-palette7, #eeeeee);border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:var(--global-palette1, #3182CE);padding-top:0px;padding-right:0px;padding-bottom:10px;padding-left:0px;}.kt-info-box14090_2b0351-ed .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box14090_2b0351-ed .kt-info-svg-icon-flip, .kt-info-box14090_2b0351-ed .kt-blocks-info-box-number{font-size:20px;}.kt-info-box14090_2b0351-ed .kt-blocks-info-box-media{color:var(--global-palette4, #2D3748);border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:3px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:7px;margin-bottom:0px;margin-left:0px;}.kt-info-box14090_2b0351-ed .kt-infobox-textcontent h6.kt-blocks-info-box-title{color:var(--global-palette4, #2D3748);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box14090_2b0351-ed .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette4, #2D3748);}.kt-info-box14090_2b0351-ed .kt-blocks-info-box-learnmore{background:transparent;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}@media all and (max-width: 1024px){.kt-info-box14090_2b0351-ed .kt-blocks-info-box-link-wrap{border-top:0px solid var(u002du002dglobal-palette7, #eeeeee);border-right:0px solid var(u002du002dglobal-palette7, #eeeeee);border-bottom:0px solid #979797;border-left:0px solid var(u002du002dglobal-palette7, #eeeeee);}}@media all and (max-width: 767px){.kt-info-box14090_2b0351-ed .kt-blocks-info-box-link-wrap{border-top:0px solid var(u002du002dglobal-palette7, #eeeeee);border-right:0px solid var(u002du002dglobal-palette7, #eeeeee);border-bottom:0px solid #979797;border-left:0px solid var(u002du002dglobal-palette7, #eeeeee);}}<\/style>                             <div class=\"wp-block-kadence-infobox kt-info-box14090_2b0351-ed info_block_01\">                             <span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-left kt-info-halign-left kb-info-box-vertical-media-align-top\">                                 <div class=\"kt-blocks-info-box-media-container\">                                 <div class=\"kt-blocks-info-box-media kt-info-media-animate-none\">                                     <div class=\"kadence-info-box-icon-container kt_info-icon-animate-none\">                                     <div class=\"kadence-info-box-icon-inner-container\">                                         <span class=\"kb-svg-icon-wrap kb-svg-icon-fe_mapPin kt-info-svg-icon\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  role=\"img\"><title>Hora<\/title><path d=\"M21 10c0 7-9 13-9 13s-9-6-9-13a9 9 0 0 1 18 0z\"\/><circle cx=\"12\" cy=\"10\" r=\"3\"\/><\/svg><\/span>                                     <\/div>                                     <\/div>                                 <\/div>                                 <\/div>                                 <div class=\"kt-infobox-textcontent\">                                 <h6 class=\"kt-blocks-info-box-title\">Lugar<\/h6>                                 <p class=\"kt-blocks-info-box-text\">Seu Social Amics del Pa\u00eds, C\/ Basea, 8 1r 1a<br>08003 Barcelona<\/p>                                 <\/div>                             <\/span>                             <\/div>                                                   <\/div>                     <\/div>                                      <\/div>             <\/div>                            <\/div><\/div>          <style>.kb-row-layout-id15198_57c2d8-c9 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id15198_57c2d8-c9 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id15198_57c2d8-c9 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, calc(70% - ((var(--global-kb-gap-md, 2rem) * 1 )\/2)))minmax(0, calc(30% - ((var(--global-kb-gap-md, 2rem) * 1 )\/2)));}.kb-row-layout-id15198_57c2d8-c9 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id15198_57c2d8-c9 > .kt-row-column-wrap{grid-template-columns:minmax(0, 2fr) minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id15198_57c2d8-c9 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id15198_57c2d8-c9 alignnone content_article_agenda wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-left-golden kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">         <style>.kadence-column15198_459565-82 > .kt-inside-inner-col,.kadence-column15198_459565-82 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column15198_459565-82 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column15198_459565-82 > .kt-inside-inner-col{flex-direction:column;}.kadence-column15198_459565-82 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column15198_459565-82 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column15198_459565-82{position:relative;}@media all and (max-width: 1024px){.kadence-column15198_459565-82 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column15198_459565-82 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>         <div class=\"wp-block-kadence-column kadence-column15198_459565-82\">             <div class=\"kt-inside-inner-col\">             <div class=\"autor_post wp-block-post-author-name\"><a href=\"https:\/\/www.amicsdelpais.com\/es\/author\/amicsdelpais\/\" target=\"_blank\" class=\"wp-block-post-author-name__link\">Amics del Pa\u00eds<\/a><\/div>             <div class=\"summary_post wp-block-post-excerpt\"><p class=\"wp-block-post-excerpt__excerpt\">Agenda Comisi\u00f3n Salud 19-10-2022 La comisi\u00f3n de Salud de Amics del Pa\u00eds organiza el debate Amics del Pa\u00eds titulado &#8216;Sistema sanitari en temps de crisi i professi\u00f3 m\u00e8dica&#8216; con el Dr. Jaume Padr\u00f3s, presidente del Colegio de M\u00e9dicos de Barcelona (COMB), y el Sr. Guillem L\u00f3pez-Casasnovas, catedr\u00e1tico de Econom\u00eda de la UPF. El acto estar\u00e1&hellip; <\/p><\/div>                           <h3>Jaume Padr\u00f3s y Guillem L\u00f3pez-Casasnovas debatir\u00e1n sobre c\u00f3mo mejorar la eficiencia y el funcionamiento del sistema de salud, tanto en la asistencia de los pacientes como en las condiciones laborales de los colectivos profesionales<\/h3>  <p>La comisi\u00f3n de Salud de Amics del Pa\u00eds organiza el debate Amics del Pa\u00eds titulado &#8216;<strong>Sistema sanitari en temps de crisi i professi\u00f3 m\u00e8dica<\/strong>&#8216; con el Dr. <strong>Jaume Padr\u00f3s<\/strong>, presidente del Colegio de M\u00e9dicos de Barcelona (COMB), y el Sr. Guillem L\u00f3pez-Casasnovas, catedr\u00e1tico de Econom\u00eda de la UPF. El acto estar\u00e1 presentado y moderado por el Dr. <strong>Antoni Guerrero<\/strong>, presidente de la comisi\u00f3n de Salud de Amics del Pa\u00eds.<\/p>   <p>El sistema sanitario catal\u00e1n vive, desde hace tiempo, sacudidas y tensiones profundas a ra\u00edz de <strong>problemas estructurales, de coordinaci\u00f3n y de financiaci\u00f3n<\/strong> que se arrastran desde la crisis de 2008 y que se han acentuado durante el estallido de la pandemia de la Covid-19. En este sentido, con la voluntad de <strong>debatir soluciones que mejoren la eficiencia y el funcionamiento del sistema de salud<\/strong>, tanto en la asistencia de los pacientes como en las condiciones laborales de los colectivos profesionales, Amics del Pa\u00eds invita a dos personalidades autorizadas y especializadas en el campo de la salud.<\/p>   <p><strong>Jaume Padr\u00f3s<\/strong> tiene una larga trayectoria profesional en el \u00e1mbito de la medicina. Fue el principal impulsor, en 1998, del Programa de Atenci\u00f3n al M\u00e9dico Enfermo (PAIMM) del Consejo de Colegios de M\u00e9dicos de Catalu\u00f1a (CCMC) y de la creaci\u00f3n, en 2001, de la Fundaci\u00f3n Galatea, que trabaja por la salud mental y el bienestar psicoemocional de los profesionales sanitarios. Actualmente compagina la presidencia del CoMB y del CCMC con el ejercicio m\u00e9dico en la sanidad p\u00fablica. En 2016 recibi\u00f3 la medalla Josep Trueta en el M\u00e9rito Sanitario y en 2017 la Creu de Sant Jordi. Tambi\u00e9n en 2021, la Academia de Ciencias M\u00e9dicas de Catalunya y Baleares acord\u00f3 nombrarle socio de honor.<\/p>   <p><strong>Guillem L\u00f3pez-Casasnovas<\/strong> es una voz experta y reconocida en la eficiencia del sector p\u00fablico, la econom\u00eda de la salud, la dependencia y los equilibrios intergeneracionales, las balanzas fiscales y la financiaci\u00f3n de las haciendas locales. En 1996 cofunda, junto con Vicente Ort\u00fan, el Centro de Investigaci\u00f3n en Econom\u00eda y Salud (CRES-UPF), centro que dirige hasta 2006. Actualmente es director, investigador principal y vocal del Consejo de Gobierno del mismo centro. Desde 2000 es miembro del Consejo Asesor del Ministerio de Sanidad y Consumo y desde un a\u00f1o m\u00e1s tarde (2021) de las Consejer\u00edas de Sanidad de Catalunya y de Illes Balears. Tambi\u00e9n ha sido presidente de la <em>International Health Economics Association<\/em>, entre 2007 y 2011, y ha ejercido de asesor experto por la Organizaci\u00f3n Mundial de la Salud (OMS) sobre las desigualdades en salud en la Uni\u00f3n Europea.<\/p>   <p><strong>El aforo es limitado y es necesaria la inscripci\u00f3n previa a trav\u00e9s del <a href='https:\/\/www.amicsdelpais.com\/es\/agenda-formulario\/debate\/debatamicsdelpais_con_jaume_padros_y_guillem_lopez_casasnovas\/458\/'>formulario<\/a><\/strong>.<\/p>                            <style>.wp-block-kadence-advancedgallery .kb-gallery-type-grid.kb-gallery-id-gallery_68d2c6c0e2aa2{margin:-5px;}.kb-gallery-type-grid.kb-gallery-id-gallery_68d2c6c0e2aa2 .kadence-blocks-gallery-item{padding:5px;}.kb-gallery-id-gallery_68d2c6c0e2aa2 .kadence-blocks-gallery-item .kb-gal-image-radius, .kb-gallery-id-gallery_68d2c6c0e2aa2 .kb-slide-item .kb-gal-image-radius img{border-radius:0px 0px 0px 0px;;}<\/style><div class=\"kb-gallery-wrap-id-gallery_68d2c6c0e2aa2 alignnone wp-block-kadence-advancedgallery\"><ul class=\"kb-gallery-ul kb-gallery-non-static kb-gallery-type-grid kb-gallery-id-gallery_68d2c6c0e2aa2 kb-gallery-caption-style-bottom-hover kb-gallery-filter-none kb-gallery-magnific-init\" data-image-filter=\"none\" data-item-selector=\".kadence-blocks-gallery-item\" data-lightbox-caption=\"true\" data-columns-xxl=\"3\" data-columns-xl=\"3\" data-columns-md=\"3\" data-columns-sm=\"2\" data-columns-xs=\"1\" data-columns-ss=\"1\"><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/www.amicsdelpais.com\/wp-content\/uploads\/public\/imgs\/1869_8o_combjaumepadros19.jpg\" data-alt=\"Jaume Padr\u00f3s\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32 kb-has-image-ratio-land32\" ><img decoding=\"async\" src=\"https:\/\/www.amicsdelpais.com\/wp-content\/uploads\/public\/imgs\/1869_8o_combjaumepadros19.jpg\"   alt=\"Jaume Padr\u00f3s\" data-full-image=\"https:\/\/www.amicsdelpais.com\/wp-content\/uploads\/public\/imgs\/1869_8o_combjaumepadros19.jpg\" data-light-image=\"https:\/\/www.amicsdelpais.com\/wp-content\/uploads\/public\/imgs\/1869_8o_combjaumepadros19.jpg\" data-id=\"\" class=\"wp-image-\"\/><\/div><\/div><\/a><\/figure><\/div><\/li><\/ul><\/div>              <style>.kb-row-layout-id22850_b19245-db > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id22850_b19245-db > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id22850_b19245-db > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:24px;padding-bottom:0px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id22850_b19245-db{background-color:#fecc8c;background-image:url('https:\/\/www.amicsdelpais.com\/wp-content\/uploads\/2025\/06\/bg_newsletter_01.svg');background-size:auto;background-position:100% 0%;background-attachment:scroll;background-repeat:repeat-y;}.kb-row-layout-id22850_b19245-db > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id22850_b19245-db > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id22850_b19245-db > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id22850_b19245-db alignnone kt-row-has-bg block_newsletter wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column22850_a01aca-24 > .kt-inside-inner-col{padding-bottom:0px;}.kadence-column22850_a01aca-24 > .kt-inside-inner-col,.kadence-column22850_a01aca-24 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column22850_a01aca-24 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column22850_a01aca-24 > .kt-inside-inner-col{flex-direction:column;}.kadence-column22850_a01aca-24 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column22850_a01aca-24 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column22850_a01aca-24{position:relative;}@media all and (max-width: 1024px){.kadence-column22850_a01aca-24 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column22850_a01aca-24 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column22850_a01aca-24\"><div class=\"kt-inside-inner-col\">\n<h2 class=\"wp-block-heading\">Suscr\u00edbete al newsletter<\/h2>\n\n\n\n<p>Suscr\u00edbete al <strong>Newsletter de Amics del Pa\u00eds<\/strong> para estar al d\u00eda de todo lo que hacemos. Recibir\u00e1s informaci\u00f3n sobre nuestras actividades, noticias destacadas y las convocatorias y novedades de las conferencias que organizamos.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f42828-o1\" lang=\"es-ES\" dir=\"ltr\" data-wpcf7-id=\"42828\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/es\/wp-json\/wp\/v2\/posts\/30851#wpcf7-f42828-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Formulario de contacto\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"42828\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.5\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"es_ES\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f42828-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<p>\t\t<div id=\"cf7md-form\" class=\"cf7md-form cf7md-spacing--tight\">\n\t\t\t<div class=\"mdc-layout-grid\">\n\t\t\t\t\t\t\t\t\n<\/p>\n<p>\t\t<div class=\"cf7md-item cf7md-text mdc-layout-grid__cell mdc-layout-grid__cell--span-12 mdc-layout-grid__cell--span-6-desktop mdc-layout-grid__cell--span-4-tablet mdc-layout-grid__cell--span-4-mobile\">\n\t\t\t<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"nom\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Nombre\" value=\"\" type=\"text\" name=\"nom\" \/><\/span><br \/>\n\t\t\t\t\t\t<div style=\"display: none;\" class=\"cf7md-text-html\">\n\t\t\t\t<div class=\"mdc-textfield\" data-mdc-auto-init=\"MDCTextfield\">\n\t\t\t\t\t<label class=\"mdc-textfield__label\"><\/label>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<br \/>\n\t\t<div class=\"cf7md-item cf7md-text mdc-layout-grid__cell mdc-layout-grid__cell--span-12 mdc-layout-grid__cell--span-6-desktop mdc-layout-grid__cell--span-4-tablet mdc-layout-grid__cell--span-4-mobile\">\n\t\t\t<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"cognoms\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Apellidos\" value=\"\" type=\"text\" name=\"cognoms\" \/><\/span><br \/>\n\t\t\t\t\t\t<div style=\"display: none;\" class=\"cf7md-text-html\">\n\t\t\t\t<div class=\"mdc-textfield\" data-mdc-auto-init=\"MDCTextfield\">\n\t\t\t\t\t<label class=\"mdc-textfield__label\"><\/label>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\n<\/p>\n<p>\t\t<div class=\"cf7md-item cf7md-text mdc-layout-grid__cell mdc-layout-grid__cell--span-12 mdc-layout-grid__cell--span-6-desktop mdc-layout-grid__cell--span-4-tablet mdc-layout-grid__cell--span-4-mobile\">\n\t\t\t<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Correo electr\u00f3nico\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span><br \/>\n\t\t\t\t\t\t<div style=\"display: none;\" class=\"cf7md-text-html\">\n\t\t\t\t<div class=\"mdc-textfield\" data-mdc-auto-init=\"MDCTextfield\">\n\t\t\t\t\t<label class=\"mdc-textfield__label\"><\/label>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<br \/>\n\t\t<div class=\"cf7md-item cf7md-text mdc-layout-grid__cell mdc-layout-grid__cell--span-12 mdc-layout-grid__cell--span-6-desktop mdc-layout-grid__cell--span-4-tablet mdc-layout-grid__cell--span-4-mobile\">\n\t\t\t<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"telefon\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-tel\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Tel\u00e9fono\" value=\"\" type=\"tel\" name=\"telefon\" \/><\/span><br \/>\n\t\t\t\t\t\t<div style=\"display: none;\" class=\"cf7md-text-html\">\n\t\t\t\t<div class=\"mdc-textfield\" data-mdc-auto-init=\"MDCTextfield\">\n\t\t\t\t\t<label class=\"mdc-textfield__label\"><\/label>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\n<\/p>\n<p>\t\t<div class=\"cf7md-item cf7md-text mdc-layout-grid__cell mdc-layout-grid__cell--span-12 mdc-layout-grid__cell--span-6-desktop mdc-layout-grid__cell--span-4-tablet mdc-layout-grid__cell--span-4-mobile\">\n\t\t\t<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"entitat\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" placeholder=\"Entidad \/ Empresa\" value=\"\" type=\"text\" name=\"entitat\" \/><\/span><br \/>\n\t\t\t\t\t\t<div style=\"display: none;\" class=\"cf7md-text-html\">\n\t\t\t\t<div class=\"mdc-textfield\" data-mdc-auto-init=\"MDCTextfield\">\n\t\t\t\t\t<label class=\"mdc-textfield__label\"><\/label>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<br \/>\n\t\t<div class=\"cf7md-item cf7md-text mdc-layout-grid__cell mdc-layout-grid__cell--span-12 mdc-layout-grid__cell--span-6-desktop mdc-layout-grid__cell--span-4-tablet mdc-layout-grid__cell--span-4-mobile\">\n\t\t\t<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"cargo\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" placeholder=\"Cargo\" value=\"\" type=\"text\" name=\"cargo\" \/><\/span><br \/>\n\t\t\t\t\t\t<div style=\"display: none;\" class=\"cf7md-text-html\">\n\t\t\t\t<div class=\"mdc-textfield\" data-mdc-auto-init=\"MDCTextfield\">\n\t\t\t\t\t<label class=\"mdc-textfield__label\"><\/label>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\n<\/p>\n<p>\t\t<div class=\"cf7md-item cf7md-accept cf7md-is-wpcf7v5 mdc-layout-grid__cell mdc-layout-grid__cell--span-12 mdc-layout-grid__cell--span-12-desktop mdc-layout-grid__cell--span-8-tablet mdc-layout-grid__cell--span-4-mobile\">\n\t\t\t\t\t\t<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"acceptance-273\"><span class=\"wpcf7-form-control wpcf7-acceptance\"><span class=\"wpcf7-list-item\"><label><input type=\"checkbox\" name=\"acceptance-273\" value=\"1\" aria-invalid=\"false\" \/><span class=\"wpcf7-list-item-label\">He le\u00eddo y acepto la <a href=\"https:\/\/www.amicsdelpais.com\/es\/avis-legal\" title=\"Tratamiento de los Datos de Car\u00e1cter Personal\" target=\"_blank\">pol\u00edtica de privacidad (GDPR)<\/a>.<\/span><\/label><\/span><\/span><\/span><br \/>\n\t\t\t<label class=\"cf7md-accept-label\"><\/label>\n\t\t\t<div style=\"display: none;\" class=\"cf7md-checkbox-html\">\n\t\t\t\t<div class=\"mdc-checkbox__background\">\n\t\t\t\t\t<svg version=\"1.1\"\n\t\t\t\t\t\tclass=\"mdc-checkbox__checkmark\"\n\t\t\t\t\t\txmlns=\"http:\/\/www.w3.org\/2000\/svg\"\n\t\t\t\t\t\tviewBox=\"0 0 24 24\"\n\t\t\t\t\t\txml:space=\"preserve\">\n\t\t\t\t\t\t<path class=\"mdc-checkbox__checkmark__path\"\n\t\t\t\t\t\t\tfill=\"none\"\n\t\t\t\t\t\t\tstroke=\"white\"\n\t\t\t\t\t\t\td=\"M1.73,12.91 8.1,19.28 22.79,4.59\"\/>\n\t\t\t\t\t<\/svg>\n\t\t\t\t\t<div class=\"mdc-checkbox__mixedmark\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<br \/>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"\" type=\"hidden\" name=\"origen\" \/><br \/>\n\t\t<div class=\"cf7md-item cf7md-submit mdc-layout-grid__cell mdc-layout-grid__cell--span-12 mdc-layout-grid__cell--span-12-desktop mdc-layout-grid__cell--span-8-tablet mdc-layout-grid__cell--span-4-mobile\">\n\t\t\t<br \/>\n<input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Subscribirme\" \/><br \/>\n\t\t\t<svg class=\"cf7md-spinner\" width=\"25px\" height=\"25px\" viewBox=\"0 0 66 66\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n\t\t\t\t<circle class=\"cf7md-spinner-path\" fill=\"none\" stroke-width=\"6\" stroke-linecap=\"round\" cx=\"33\" cy=\"33\" r=\"30\"><\/circle>\n\t\t\t<\/svg>\n\t\t<\/div>\n\t\t<br \/>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n\n<\/div><\/div>\n\n<\/div><\/div>             <\/div>         <\/div>                   <style>.kadence-column15198_b55ca3-7f > .kt-inside-inner-col,.kadence-column15198_b55ca3-7f > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column15198_b55ca3-7f > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column15198_b55ca3-7f > .kt-inside-inner-col{flex-direction:column;}.kadence-column15198_b55ca3-7f > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column15198_b55ca3-7f > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column15198_b55ca3-7f{position:relative;}@media all and (max-width: 1024px){.kadence-column15198_b55ca3-7f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column15198_b55ca3-7f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>         <div class=\"wp-block-kadence-column kadence-column15198_b55ca3-7f\">             <div class=\"kt-inside-inner-col\">                                  <style>.kadence-column15319_c8bedf-02 > .kt-inside-inner-col,.kadence-column15319_c8bedf-02 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column15319_c8bedf-02 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column15319_c8bedf-02 > .kt-inside-inner-col{flex-direction:column;}.kadence-column15319_c8bedf-02 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column15319_c8bedf-02 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column15319_c8bedf-02{position:relative;}@media all and (max-width: 1024px){.kadence-column15319_c8bedf-02 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column15319_c8bedf-02 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style> <div class=\"wp-block-kadence-column kadence-column15319_c8bedf-02 sidebar_block_01\">     <div class=\"kt-inside-inner-col\">         <h5 class=\"wp-block-heading\">Enlaces relacionados<\/h5>                           <ul class=\"wp-block-list links_relacionats_list\">         <li><a href=\"https:\/\/www.amicsdelpais.com\/ca\/publicacions\/covid19_escenaris_de_futur\/891\/\" data-type=\"link\" data-id=\"https:\/\/www.amicsdelpais.com\/ca\/publicacions\/covid19_escenaris_de_futur\/891\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">&#8216;Covid-19: escenaris de futur&#8217; con Antoni Trilla<\/a><\/li>              <li><a href=\"https:\/\/www.amicsdelpais.com\/ca\/publicacions\/reflexions_etiques_sobre_la_pandemia\/863\/\" data-type=\"link\" data-id=\"https:\/\/www.amicsdelpais.com\/ca\/publicacions\/reflexions_etiques_sobre_la_pandemia\/863\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">&#8216;Reflexions \u00e8tiques sobre la pand\u00e8mia&#8217; con Antoni Broggi<\/a><\/li>                 <\/ul>                      <\/div>     <\/div>                  <\/div>         <\/div>                  <\/div><\/div>                   <p><\/p>         ","protected":false},"excerpt":{"rendered":"<p>Agenda Comisi\u00f3n Salud 19-10-2022 La comisi\u00f3n de Salud de Amics del Pa\u00eds organiza el debate Amics del Pa\u00eds titulado &#8216;Sistema sanitari en temps de crisi i professi\u00f3 m\u00e8dica&#8216; con el Dr. Jaume Padr\u00f3s, presidente del Colegio de M\u00e9dicos de Barcelona (COMB), y el Sr. Guillem L\u00f3pez-Casasnovas, catedr\u00e1tico de Econom\u00eda de la UPF. El acto estar\u00e1 presentado y moderado por el Dr. Antoni Guerrero, presidente de la comisi\u00f3n de Salud de Amics del Pa\u00eds. El sistema sanitario catal\u00e1n vive, desde hace tiempo, sacudidas y tensiones profundas a ra\u00edz de problemas estructurales, de coordinaci\u00f3n y de financiaci\u00f3n que se arrastran desde la crisis de 2008 y que se han acentuado durante el estallido de la pandemia de la Covid-19. En este sentido, con la voluntad de debatir soluciones que mejoren la eficiencia y el funcionamiento del sistema de salud, tanto en la asistencia de los pacientes como en las condiciones laborales de los colectivos profesionales, Amics del Pa\u00eds invita a dos personalidades autorizadas y especializadas en el campo de la salud. Jaume Padr\u00f3s tiene una larga trayectoria profesional en el \u00e1mbito de la medicina. Fue el principal impulsor, en 1998, del Programa de Atenci\u00f3n al M\u00e9dico Enfermo (PAIMM) del Consejo de Colegios de M\u00e9dicos de Catalu\u00f1a (CCMC) y de la creaci\u00f3n, en 2001, de la Fundaci\u00f3n Galatea, que trabaja por la salud mental y el bienestar psicoemocional de los profesionales sanitarios. Actualmente compagina la presidencia del CoMB y del CCMC con el ejercicio m\u00e9dico en la sanidad p\u00fablica. En 2016 recibi\u00f3 la medalla Josep Trueta en el M\u00e9rito Sanitario y en 2017 la Creu de Sant Jordi. Tambi\u00e9n en 2021, la Academia de Ciencias M\u00e9dicas de Catalunya y Baleares acord\u00f3 nombrarle socio de honor. Guillem L\u00f3pez-Casasnovas es una voz experta y reconocida en la eficiencia del sector p\u00fablico, la econom\u00eda de la&#8230;<\/p>\n","protected":false},"author":186,"featured_media":30142,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"categories":[241,724,120,248,767],"tags":[],"class_list":["post-30851","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agenda-2","category-comision-de-salud-agenda","category-conferencias","category-debate","category-salut-publicacions-es"],"taxonomy_info":{"category":[{"value":241,"label":"Agenda"},{"value":724,"label":"Comisi\u00f3n de Salud Agenda"},{"value":120,"label":"Conferencias"},{"value":248,"label":"Debate"},{"value":767,"label":"Salud - Publicaciones"}]},"featured_image_src_large":["https:\/\/www.amicsdelpais.com\/wp-content\/uploads\/2025\/09\/1867_cb_az8q7410-2-1024x683.jpg",1024,683,true],"author_info":{"display_name":"Amics del Pa\u00eds","author_link":"https:\/\/www.amicsdelpais.com\/es\/author\/amicsdelpais\/"},"comment_info":0,"category_info":[{"term_id":241,"name":"Agenda","slug":"agenda-2","term_group":0,"term_taxonomy_id":241,"taxonomy":"category","description":"","parent":0,"count":481,"filter":"raw","cat_ID":241,"category_count":481,"category_description":"","cat_name":"Agenda","category_nicename":"agenda-2","category_parent":0},{"term_id":724,"name":"Comisi\u00f3n de Salud Agenda","slug":"comision-de-salud-agenda","term_group":0,"term_taxonomy_id":724,"taxonomy":"category","description":"","parent":241,"count":15,"filter":"raw","cat_ID":724,"category_count":15,"category_description":"","cat_name":"Comisi\u00f3n de Salud Agenda","category_nicename":"comision-de-salud-agenda","category_parent":241},{"term_id":120,"name":"Conferencias","slug":"conferencias","term_group":0,"term_taxonomy_id":120,"taxonomy":"category","description":"","parent":0,"count":478,"filter":"raw","cat_ID":120,"category_count":478,"category_description":"","cat_name":"Conferencias","category_nicename":"conferencias","category_parent":0},{"term_id":248,"name":"Debate","slug":"debate","term_group":0,"term_taxonomy_id":248,"taxonomy":"category","description":"","parent":241,"count":58,"filter":"raw","cat_ID":248,"category_count":58,"category_description":"","cat_name":"Debate","category_nicename":"debate","category_parent":241},{"term_id":767,"name":"Salud - Publicaciones","slug":"salut-publicacions-es","term_group":0,"term_taxonomy_id":767,"taxonomy":"category","description":"","parent":771,"count":12,"filter":"raw","cat_ID":767,"category_count":12,"category_description":"","cat_name":"Salud - Publicaciones","category_nicename":"salut-publicacions-es","category_parent":771}],"tag_info":false,"_links":{"self":[{"href":"https:\/\/www.amicsdelpais.com\/es\/wp-json\/wp\/v2\/posts\/30851","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.amicsdelpais.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.amicsdelpais.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.amicsdelpais.com\/es\/wp-json\/wp\/v2\/users\/186"}],"replies":[{"embeddable":true,"href":"https:\/\/www.amicsdelpais.com\/es\/wp-json\/wp\/v2\/comments?post=30851"}],"version-history":[{"count":1,"href":"https:\/\/www.amicsdelpais.com\/es\/wp-json\/wp\/v2\/posts\/30851\/revisions"}],"predecessor-version":[{"id":34258,"href":"https:\/\/www.amicsdelpais.com\/es\/wp-json\/wp\/v2\/posts\/30851\/revisions\/34258"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.amicsdelpais.com\/es\/wp-json\/wp\/v2\/media\/30142"}],"wp:attachment":[{"href":"https:\/\/www.amicsdelpais.com\/es\/wp-json\/wp\/v2\/media?parent=30851"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.amicsdelpais.com\/es\/wp-json\/wp\/v2\/categories?post=30851"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.amicsdelpais.com\/es\/wp-json\/wp\/v2\/tags?post=30851"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}