{"id":22228,"date":"2011-10-13T00:00:00","date_gmt":"2011-10-12T22:00:00","guid":{"rendered":"https:\/\/new.barcelonatribuna.com\/la_salida_de_la_crisis\/"},"modified":"2011-10-13T00:00:00","modified_gmt":"2011-10-12T22:00:00","slug":"la_salida_de_la_crisis","status":"publish","type":"post","link":"https:\/\/www.amicsdelpais.com\/es\/la_salida_de_la_crisis\/","title":{"rendered":"La salida de la crisis"},"content":{"rendered":"         <p class=\"link_ariadna wp-block-paragraph\"><a href=\"https:\/\/www.amicsdelpais.com\/es\/publicaciones\">Publicaciones<\/a><\/p>                   <h1 class=\"wp-block-post-title\">La salida de la crisis<\/h1>          <style>.kb-row-layout-id15198_fd4370-d2 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id15198_fd4370-d2 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id15198_fd4370-d2 > .kt-row-column-wrap{column-gap:40px;row-gap:var(--global-kb-gap-md, 2rem);padding-top:0px;padding-bottom:24px;grid-template-columns:minmax(0, calc(70% - ((40px * 1 )\/2)))minmax(0, calc(30% - ((40px * 1 )\/2)));}.kb-row-layout-id15198_fd4370-d2 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id15198_fd4370-d2 > .kt-row-column-wrap{grid-template-columns:minmax(0, 2fr) minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id15198_fd4370-d2 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id15198_fd4370-d2 alignnone header_article_agenda wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-left-golden kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">         <style>.kadence-column15198_b1d053-1d > .kt-inside-inner-col,.kadence-column15198_b1d053-1d > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column15198_b1d053-1d > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column15198_b1d053-1d > .kt-inside-inner-col{flex-direction:column;}.kadence-column15198_b1d053-1d > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column15198_b1d053-1d > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column15198_b1d053-1d{position:relative;}@media all and (max-width: 1024px){.kadence-column15198_b1d053-1d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column15198_b1d053-1d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>         <div class=\"wp-block-kadence-column kadence-column15198_b1d053-1d\"><div class=\"kt-inside-inner-col\"><figure class=\"wp-block-post-featured-image\"><img loading=\"lazy\" decoding=\"async\" width=\"839\" height=\"559\" src=\"https:\/\/www.amicsdelpais.com\/wp-content\/uploads\/2025\/07\/default_image_amics_del_pais-2.png\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"\" style=\"object-fit:cover;\" srcset=\"https:\/\/www.amicsdelpais.com\/wp-content\/uploads\/2025\/07\/default_image_amics_del_pais-2.png 839w, https:\/\/www.amicsdelpais.com\/wp-content\/uploads\/2025\/07\/default_image_amics_del_pais-2-300x200.png 300w, https:\/\/www.amicsdelpais.com\/wp-content\/uploads\/2025\/07\/default_image_amics_del_pais-2-768x512.png 768w, https:\/\/www.amicsdelpais.com\/wp-content\/uploads\/2025\/07\/default_image_amics_del_pais-2-600x400.png 600w\" sizes=\"auto, (max-width: 839px) 100vw, 839px\" \/><\/figure><\/div><\/div>                   <style>.kadence-column15494_3829e6-92 > .kt-inside-inner-col,.kadence-column15494_3829e6-92 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column15494_3829e6-92 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column15494_3829e6-92 > .kt-inside-inner-col{flex-direction:column;}.kadence-column15494_3829e6-92 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column15494_3829e6-92 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column15494_3829e6-92{position:relative;}@media all and (max-width: 1024px){.kadence-column15494_3829e6-92 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column15494_3829e6-92 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>         <div class=\"wp-block-kadence-column kadence-column15494_3829e6-92\">             <div class=\"kt-inside-inner-col\">                                  <style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box14181_ae7a89-85 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box14181_ae7a89-85 .kt-blocks-info-box-link-wrap{border-top:0px solid var(u002du002dglobal-palette7, #eeeeee);border-right:0px solid var(u002du002dglobal-palette7, #eeeeee);border-bottom:1px solid #979797;border-left:0px solid var(u002du002dglobal-palette7, #eeeeee);border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:var(--global-palette1, #3182CE);padding-top:0px;padding-right:0px;padding-bottom:10px;padding-left:0px;margin-bottom:10px;}.kt-info-box14181_ae7a89-85 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box14181_ae7a89-85 .kt-info-svg-icon-flip, .kt-info-box14181_ae7a89-85 .kt-blocks-info-box-number{font-size:20px;}.kt-info-box14181_ae7a89-85 .kt-blocks-info-box-media{color:var(--global-palette4, #2D3748);border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:3px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:7px;margin-bottom:0px;margin-left:0px;}.kt-info-box14181_ae7a89-85 .kt-infobox-textcontent h6.kt-blocks-info-box-title{color:var(--global-palette4, #2D3748);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box14181_ae7a89-85 .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette4, #2D3748);}.kt-info-box14181_ae7a89-85 .kt-blocks-info-box-learnmore{background:transparent;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}@media all and (max-width: 1024px){.kt-info-box14181_ae7a89-85 .kt-blocks-info-box-link-wrap{border-top:0px solid var(u002du002dglobal-palette7, #eeeeee);border-right:0px solid var(u002du002dglobal-palette7, #eeeeee);border-bottom:1px solid #979797;border-left:0px solid var(u002du002dglobal-palette7, #eeeeee);}}@media all and (max-width: 767px){.kt-info-box14181_ae7a89-85 .kt-blocks-info-box-link-wrap{border-top:0px solid var(u002du002dglobal-palette7, #eeeeee);border-right:0px solid var(u002du002dglobal-palette7, #eeeeee);border-bottom:1px solid #979797;border-left:0px solid var(u002du002dglobal-palette7, #eeeeee);}}<\/style> <div class=\"wp-block-kadence-infobox kt-info-box14181_ae7a89-85 info_block_01\">     <span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-left kt-info-halign-left kb-info-box-vertical-media-align-top\">         <div class=\"kt-blocks-info-box-media-container\">             <div class=\"kt-blocks-info-box-media kt-info-media-animate-none\">                 <div class=\"kadence-info-box-icon-container kt-info-icon-animate-none\">                     <div class=\"kadence-info-box-icon-inner-container\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_book kt-info-svg-icon\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  role=\"img\"><title>Hora<\/title><path d=\"M4 19.5A2.5 2.5 0 0 1 6.5 17H20\"\/><path d=\"M6.5 2H20v20H6.5A2.5 2.5 0 0 1 4 19.5v-15A2.5 2.5 0 0 1 6.5 2z\"\/><\/svg><\/span><\/div>                 <\/div>             <\/div>         <\/div>         <div class=\"kt-infobox-textcontent\">             <h6 class=\"kt-blocks-info-box-title\">Tipo de publicaci\u00f3n<\/h6><p class=\"kt-blocks-info-box-text\"><a href=\"\/publicacions\/articulos\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Art\u00edculos<\/a><\/p>        <\/div>     <\/span> <\/div>                  <style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box15198_70ed2d-ec .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box15198_70ed2d-ec .kt-blocks-info-box-link-wrap{border-top:0px solid var(u002du002dglobal-palette7, #eeeeee);border-right:0px solid var(u002du002dglobal-palette7, #eeeeee);border-bottom:0px solid #979797;border-left:0px solid var(u002du002dglobal-palette7, #eeeeee);border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:var(--global-palette1, #3182CE);padding-top:0px;padding-right:0px;padding-bottom:10px;padding-left:0px;}.kt-info-box15198_70ed2d-ec .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box15198_70ed2d-ec .kt-info-svg-icon-flip, .kt-info-box15198_70ed2d-ec .kt-blocks-info-box-number{font-size:20px;}.kt-info-box15198_70ed2d-ec .kt-blocks-info-box-media{color:var(--global-palette4, #2D3748);border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:3px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:7px;margin-bottom:0px;margin-left:0px;}.kt-info-box15198_70ed2d-ec .kt-infobox-textcontent h6.kt-blocks-info-box-title{color:var(--global-palette4, #2D3748);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box15198_70ed2d-ec .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette4, #2D3748);}.kt-info-box15198_70ed2d-ec .kt-blocks-info-box-learnmore{background:transparent;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}@media all and (max-width: 1024px){.kt-info-box15198_70ed2d-ec .kt-blocks-info-box-link-wrap{border-top:0px solid var(u002du002dglobal-palette7, #eeeeee);border-right:0px solid var(u002du002dglobal-palette7, #eeeeee);border-bottom:0px solid #979797;border-left:0px solid var(u002du002dglobal-palette7, #eeeeee);}}@media all and (max-width: 767px){.kt-info-box15198_70ed2d-ec .kt-blocks-info-box-link-wrap{border-top:0px solid var(u002du002dglobal-palette7, #eeeeee);border-right:0px solid var(u002du002dglobal-palette7, #eeeeee);border-bottom:0px solid #979797;border-left:0px solid var(u002du002dglobal-palette7, #eeeeee);}}<\/style> <div class=\"wp-block-kadence-infobox kt-info-box15198_70ed2d-ec info_block_01\">     <span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-left kt-info-halign-left kb-info-box-vertical-media-align-top\">         <div class=\"kt-blocks-info-box-media-container\">             <div class=\"kt-blocks-info-box-media kt-info-media-animate-none\">                 <div class=\"kadence-info-box-icon-container kt-info-icon-animate-none\">                     <div class=\"kadence-info-box-icon-inner-container\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_calendar kt-info-svg-icon\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  role=\"img\"><title>Hora<\/title><rect x=\"3\" y=\"4\" width=\"18\" height=\"18\" rx=\"2\" ry=\"2\"\/><line x1=\"16\" y1=\"2\" x2=\"16\" y2=\"6\"\/><line x1=\"8\" y1=\"2\" x2=\"8\" y2=\"6\"\/><line x1=\"3\" y1=\"10\" x2=\"21\" y2=\"10\"\/><\/svg><\/span><\/div>                 <\/div>             <\/div>         <\/div>         <div class=\"kt-infobox-textcontent\">             <h6 class=\"kt-blocks-info-box-title\">Data<\/h6>             <p class=\"kt-blocks-info-box-text\">13-10-2011<\/p>         <\/div>     <\/span> <\/div>              <\/div>                      <\/div>                    <\/div><\/div>          <style>.kb-row-layout-id15198_57c2d8-c9 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id15198_57c2d8-c9 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id15198_57c2d8-c9 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, calc(70% - ((var(--global-kb-gap-md, 2rem) * 1 )\/2)))minmax(0, calc(30% - ((var(--global-kb-gap-md, 2rem) * 1 )\/2)));}.kb-row-layout-id15198_57c2d8-c9 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id15198_57c2d8-c9 > .kt-row-column-wrap{grid-template-columns:minmax(0, 2fr) minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id15198_57c2d8-c9 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id15198_57c2d8-c9 alignnone content_article_agenda wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-left-golden kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">         <style>.kadence-column15198_459565-82 > .kt-inside-inner-col,.kadence-column15198_459565-82 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column15198_459565-82 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column15198_459565-82 > .kt-inside-inner-col{flex-direction:column;}.kadence-column15198_459565-82 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column15198_459565-82 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column15198_459565-82{position:relative;}@media all and (max-width: 1024px){.kadence-column15198_459565-82 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column15198_459565-82 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>         <div class=\"wp-block-kadence-column kadence-column15198_459565-82\">             <div class=\"kt-inside-inner-col\">             <div class=\"autor_post wp-block-post-author-name\"><a href=\"https:\/\/www.amicsdelpais.com\/es\/author\/ramon-palacio\/\" target=\"_blank\" class=\"wp-block-post-author-name__link\">Ramon Palacio<\/a><\/div>             <div class=\"summary_post wp-block-post-excerpt\"><p class=\"wp-block-post-excerpt__excerpt\">Ramon Palacio, enginiero y Vicepresidente del Cercle per al Coneixement, reflexiona sobre la crisis econ\u00f3mica actual y propone medidas econ\u00f3micas y sociales necesarias para poder salir de ella. <\/p><\/div>                           Deberemos ser optimistas, \u00bfverdad? La crisis se acabar\u00e1. <b>Se acabar\u00e1 pero con un cambio de modelo pol\u00edtico y econ\u00f3mico<\/b>.  Empecemos por el principio, por entender que es lo qu\u00e9 pasa.   \u00bfLa crisis es global? Global s\u00ed, pero mundial no. La crisis es europea y norteamericana, o como mucho, de la OECD (Europa, Norteam\u00e9rica, Australia y Nueva Zelanda, Jap\u00f3n y Korea). Los BRIC, los pa\u00edses emergentes (Resto de Asia, Latinoam\u00e9rica,\u2026) no sufren \u201cesta\u201d crisis, ellos siguen creciendo y tendr\u00e1n sus crisis de crecimiento, que ser\u00e1n distintas.  \u00bfQuien la caus\u00f3? La global se origin\u00f3 en y por los USA, por su burbuja inmobiliaria, a saber (1) excederse en la construcci\u00f3n residencial, con precios crecientes que hac\u00edan subir tambi\u00e9n de precio la vivienda de segunda mano,  (2) excederse en el cr\u00e9dito hipotecario para comprar estos bienes, con la \u00fanica garant\u00eda de su mayor precio en el futuro (bienes de valor menguante y de  precio creciente), y (3) adem\u00e1s \u201cexportar\u201d estas hipotecas contaminadas y \u201cempaquetadas\u201d (activos t\u00f3xicos, les llaman) a los bancos del resto del mundo.  \u00bfQu\u00e9 ocurre en Europa? Que las instituciones financieras, los  bancos, han incorporado activos t\u00f3xicos. Que las empresas dependen de los bancos para financiar su \u201cd\u00eda a d\u00eda\u201d, que han cerrado empresas, que  la econom\u00eda se ha ralentizado, que los ingresos fiscales de los Estados han disminuido, que los Estados se han sobre-endeudado.  Pero, los Estados han salvado a (sus) bancos e instituciones financieras, y por el contrario, estas instituciones financieras \u00bflas mismas? exigen intereses crecientes a los Estados por esta deuda, entrando en una espiral de deuda insostenible. \u00bfSer\u00e1 verdad que \u201cGoldman Sachs rules the world\u201d?  \u00bfY en Espa\u00f1a? Pues lo mismo \u00a1pero m\u00e1s!, promoviendo la compra de vivienda a cr\u00e9dito, construyendo tantas viviendas por a\u00f1o como Alemania, Francia, Italia  y Reino Unido juntos, sobre-endeud\u00e1ndonos como  familias, y con instituciones financieras en el monocultivo de la construcci\u00f3n, sobre-endeudadas para prestar hipotecas, con el \u201caval\u201d que el mismo bien hipotecado subir\u00e1 de precio, que viejo vale m\u00e1s que  nuevo, y cuando la burbuja rompe, con un Estado en d\u00e9ficit presupuestario y sobre-endeudado, en manos de \u201clos mercados\u201d. En suma, <b>econom\u00eda especulativa<\/b>.  En Espa\u00f1a, la crisis global y la propia se han sumado \u201cen fase\u201d.  Adem\u00e1s, nos cre\u00edmos que crec\u00edamos, nos sobraba dinero p\u00fablico y lo repartimos en porciones de 400\u20ac en las \u00faltimas elecciones. De la eficacia, la eficiencia y la productividad s\u00f3lo hablaron cuatro imaginativos.  Lo que est\u00e1 claro es que esta crisis no es una broma, es la m\u00e1s seria desde 1929, y va a cambiar el mundo occidental y el planeta. En un proceso de evoluci\u00f3n, los sucesivos estadios no anulan los anteriores, sino que los integran y superan (Hegel). Y cuando esto no sucede, el sistema se vuelve inestable y no sostenible. Por encima de la econom\u00eda productiva ha aparecido el capital financiero, de naturaleza especulativa. Y <b>las organizaciones empresariales no han evolucionado y no representan al capital financiero, y los sindicatos tampoco han evolucionado y siguen creyendo que los empresarios son sus enemigos<\/b>.  El capital financiero es \u201cgrande\u201d, pesa 6 veces el PIB mundial (ver 1),  \u201cse mueve r\u00e1pido\u201d, 70 veces el PIB mundial en un a\u00f1o (ver 2 y 3),  y es \u201cespeculativo\u201d, s\u00f3lo el 2% conlleva intercambio comercial real (ver 4).  Resulta que vivimos en un mundo que limita (y mucho) los movimientos de personas (inmigraci\u00f3n), limita (un poco) los movimientos de productos (aduanas, aranceles) y no limita nada,  ni siquiera grava fiscalmente,  los movimientos de capitales, que son puros movimientos de informaci\u00f3n, instant\u00e1neos, facilitados por las tecnolog\u00edas TIC. Vivimos en un mundo que los gobiernos no gobiernan (lo hacen los mercados), que los sindicatos defienden a los que ya est\u00e1n asentados (funcionarios, empleados de grandes compa\u00f1\u00edas) e ignoran a los d\u00e9biles (los aut\u00f3nomos, los parados, los j\u00f3venes, con un 45% de paro en Espa\u00f1a), un mundo en el que hay crisis de representaci\u00f3n pol\u00edtica y de prestigio de la \u201cclase\u201d pol\u00edtica, en que las instituciones sociales no consiguen compensar este desprestigio, en el que los \u201cmedia\u201d son  arma pol\u00edtica y se construyen sobre la manipulaci\u00f3n. Vivimos en una sociedad en proceso de individualizaci\u00f3n y desestructuraci\u00f3n. Y corremos el riesgo de crear una fractura social, con dos sociedades, la que ha superado la crisis y la que se ha hundido, sin trabajo y sin recursos.  \u00bfQu\u00e9 se est\u00e1 haciendo mal?  En primer lugar, seguir alimentando la fiera, seguir alimentando a los \u201can\u00f3nimos\u201d mercados financieros. \u00bfo no son an\u00f3nimos y tienen nombres y apellidos? \u00bfcu\u00e1les?.  En segundo lugar, incrementar la distancia entre representados y representantes, \u201ctodo para el pueblo pero sin el pueblo\u201d, reformas expr\u00e9s e impuestas de la Constituci\u00f3n, prebendas pol\u00edticas a un grupo de escogidos (magistrados, parlamentarios, gobiernos,..)  En tercer lugar, reducir en inversi\u00f3n de futuro, reducir en educaci\u00f3n,  (tanto en escuelas como en universidades) y reducir en investigaci\u00f3n. Dedicar lo poco que tenemos a gastar en vez de invertir.  \u00bfQu\u00e9 hay que hacer para salir?  <b>Un cambio de \u201cmaneras\u201d<\/b>, gobernar la empresa, gobernar el pa\u00eds con criterios de eficacia, eficiencia, mesura y proporcionalidad. Exigencia de responsabilidades a los gestores p\u00fablicos y privados. Uso de tecnolog\u00eda para la eficiencia. Transparencia en las acciones y en el proceso de toma de decisiones. Recuperar la credibilidad pol\u00edtica. Priorizar inversi\u00f3n frente al gasto. Priorizar la econom\u00eda productiva. Dejar de empecinarse en el error de una econom\u00eda especulativa. M\u00e1s ingenieros y menos abogados (con perd\u00f3n), m\u00e1s empresa y menos asesores (con perd\u00f3n), m\u00e1s comercio y menos bancos (con perd\u00f3n). Disminuir la dependencia hacia el sistema financiero. Reducir los retrasos en los pagos. Que la Administraci\u00f3n d\u00e9 ejemplo. Redefinir el mercado de trabajo. Unificar en lo posible la actual doble escala de contrataci\u00f3n, la \u201cindefinida\u201d y protegida frente a la \u201ceventual\u201d y desprotegida, en condiciones intermedias entre ambas.  <b>Algunas de estas propuestas requieren acciones coordinadas a nivel mundial (ex. tasas sobre transacciones financieras) pero otras pueden realizarse a los distintos niveles de gobierno, europeo, espa\u00f1ol, catal\u00e1n (cambios de maneras, transparencia, inversi\u00f3n en capital humano, legislaci\u00f3n).<\/b>   (1) Informe ATTAC, El 94% de las transacciones financieras son especulativas ATTAC, junio 2011 , <a target=\"_new\" href=\"http:\/\/www.attacmadrid.org\/?p=4882\" rel=\"noopener\">www.attacmadrid.org<\/a>  El capital financiero a nivel mundial tiene un valor aproximado de m\u00e1s de 337 billones de d\u00f3lares, lo que representa 6.25 veces el valor de la producci\u00f3n mundial de mercanc\u00edas y servicios que se produjo durante 2007, que fue de poco m\u00e1s de 54 billones de d\u00f3lares. La suma de ese capital financiero en parte se deriva de los excedentes de capital que se han acumulado desde el siglo anterior, pero en parte no son existentes, pues esta cantidad es inflada por la especulaci\u00f3n; es capital ficticio, como lo denominada Marx, en su pleno sentido de la palabra.  (2) Dictamen Comit\u00e9 Econ\u00f3mico y Social Europeo, 18 febrero 2010 <a target=\"_new\" href=\"http:\/\/periodismohumano.com\/files\/2011\/02\/ITF.-Dictamen-CESEU.pdf\" rel=\"noopener\">periodismohumano.com<\/a>  El importe total del conjunto de transacciones financieras se ha incrementado, pasando de representar aproximadamente quince veces el valor del PIB mundial en 1990 a hacerlo 70 veces en 2007. Dado que no se han producido pr\u00e1cticamente variaciones en el valor de las operaciones al contado en relaci\u00f3n con el PIB, esto implica que el incremento del 400 % en las transacciones financieras corresponde casi por completo a los derivados y, principalmente, a los relacionados con los tipos de inter\u00e9s. Durante el segundo semestre de 2008 se registr\u00f3 un descenso en el negocio de los derivados, aunque su volumen comenz\u00f3 a incrementarse nuevamente en la primera mitad de 2009. No parece, pues, que hayan cambiado mucho las cosas en el comportamiento del sector financiero.  (3) Fundaci\u00f3n Ideas, Informe para el G-20, Mayo 2010 <a target=\"_new\" href=\"http:\/\/www.fundacionideas.es\/sites\/default\/files\/pdf\/I-Impuestos_frenar_especulacion_financiera-Ec.pdf\" rel=\"noopener\">www.fundacionideas.es<\/a>  Existe un consenso generalizado sobre el excesivo tama\u00f1o que ha alcanzado el sector financiero en la econom\u00eda global: el volumen de operaciones financieras ha pasado de ser 25 veces el PIB mundial a mediados de los a\u00f1os noventa, hasta representar actualmente 70 veces el PIB mundial. La mayor parte de este crecimiento se deriva de operaciones especulativas a plazos extremadamente cortos (incluso inferiores a un d\u00eda), que son escasamente productivas y que encierran un enorme potencial de distorsi\u00f3n sobre los mercados financieros y, por extensi\u00f3n, tambi\u00e9n sobre los mer\u00accados reales.   (4) Ugt, mayo 2011  <a target=\"_new\" href=\"http:\/\/www.fundacionluistilve.com\/pdf\/sistema%20financiero.pdf\" rel=\"noopener\">www.fundacionluistilve.com<\/a>  El sector financiero ha sido uno de los granes beneficiados del proceso de globalizaci\u00f3n. La creciente liberalizaci\u00f3n de los mercados de capitales ha supuesto un crecimiento sin precedentes de los intercambios financieros. Se estima que, a pesar de la crisis, el volumen total de dichos intercambios supera actualmente el 70% del PIB mundial. Otro dato que da muestra del enorme volumen de capitales que mueve el sector lo podemos extraer del Banco Internacional de Pagos de Basilea, seg\u00fan el cual cada d\u00eda se realizan operaciones cambiarias por un valor total de alrededor de cuatro billones de d\u00f3lares. Sin embargo, un dato m\u00e1s revelador, si cabe, lo encontramos al comprobar que pese a la enorme cantidad de capital y de activos que se mueven diariamente, tan solo un 2% conllevan intercambios comerciales asociados, lo que demuestra el alejamiento que existe entre el la econom\u00eda real y la econom\u00eda financiera.                                          <style>.kb-row-layout-id22850_b19245-db > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id22850_b19245-db > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id22850_b19245-db > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:24px;padding-bottom:0px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id22850_b19245-db{background-color:#fecc8c;background-image:url('https:\/\/www.amicsdelpais.com\/wp-content\/uploads\/2025\/06\/bg_newsletter_01.svg');background-size:auto;background-position:100% 0%;background-attachment:scroll;background-repeat:repeat-y;}.kb-row-layout-id22850_b19245-db > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id22850_b19245-db > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id22850_b19245-db > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id22850_b19245-db alignnone kt-row-has-bg block_newsletter wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column22850_a01aca-24 > .kt-inside-inner-col{padding-bottom:0px;}.kadence-column22850_a01aca-24 > .kt-inside-inner-col,.kadence-column22850_a01aca-24 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column22850_a01aca-24 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column22850_a01aca-24 > .kt-inside-inner-col{flex-direction:column;}.kadence-column22850_a01aca-24 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column22850_a01aca-24 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column22850_a01aca-24{position:relative;}@media all and (max-width: 1024px){.kadence-column22850_a01aca-24 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column22850_a01aca-24 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column22850_a01aca-24\"><div class=\"kt-inside-inner-col\">\n<h2 class=\"wp-block-heading\">Suscr\u00edbete al newsletter<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Suscr\u00edbete al <strong>Newsletter de Amics del Pa\u00eds<\/strong> para estar al d\u00eda de todo lo que hacemos. Recibir\u00e1s informaci\u00f3n sobre nuestras actividades, noticias destacadas y las convocatorias y novedades de las conferencias que organizamos.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f42828-o1\" lang=\"es-ES\" dir=\"ltr\" data-wpcf7-id=\"42828\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/es\/wp-json\/wp\/v2\/posts\/22228#wpcf7-f42828-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Formulario de contacto\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"42828\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.6\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"es_ES\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f42828-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<p>\t\t<div id=\"cf7md-form\" class=\"cf7md-form cf7md-spacing--tight\">\n\t\t\t<div class=\"mdc-layout-grid\">\n\t\t\t\t\t\t\t\t\n<\/p>\n<p>\t\t<div class=\"cf7md-item cf7md-text mdc-layout-grid__cell mdc-layout-grid__cell--span-12 mdc-layout-grid__cell--span-6-desktop mdc-layout-grid__cell--span-4-tablet mdc-layout-grid__cell--span-4-mobile\">\n\t\t\t<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"nom\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Nombre\" value=\"\" type=\"text\" name=\"nom\" \/><\/span><br \/>\n\t\t\t\t\t\t<div style=\"display: none;\" class=\"cf7md-text-html\">\n\t\t\t\t<div class=\"mdc-textfield\" data-mdc-auto-init=\"MDCTextfield\">\n\t\t\t\t\t<label class=\"mdc-textfield__label\"><\/label>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<br \/>\n\t\t<div class=\"cf7md-item cf7md-text mdc-layout-grid__cell mdc-layout-grid__cell--span-12 mdc-layout-grid__cell--span-6-desktop mdc-layout-grid__cell--span-4-tablet mdc-layout-grid__cell--span-4-mobile\">\n\t\t\t<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"cognoms\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Apellidos\" value=\"\" type=\"text\" name=\"cognoms\" \/><\/span><br \/>\n\t\t\t\t\t\t<div style=\"display: none;\" class=\"cf7md-text-html\">\n\t\t\t\t<div class=\"mdc-textfield\" data-mdc-auto-init=\"MDCTextfield\">\n\t\t\t\t\t<label class=\"mdc-textfield__label\"><\/label>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\n<\/p>\n<p>\t\t<div class=\"cf7md-item cf7md-text mdc-layout-grid__cell mdc-layout-grid__cell--span-12 mdc-layout-grid__cell--span-6-desktop mdc-layout-grid__cell--span-4-tablet mdc-layout-grid__cell--span-4-mobile\">\n\t\t\t<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Correo electr\u00f3nico\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span><br \/>\n\t\t\t\t\t\t<div style=\"display: none;\" class=\"cf7md-text-html\">\n\t\t\t\t<div class=\"mdc-textfield\" data-mdc-auto-init=\"MDCTextfield\">\n\t\t\t\t\t<label class=\"mdc-textfield__label\"><\/label>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<br \/>\n\t\t<div class=\"cf7md-item cf7md-text mdc-layout-grid__cell mdc-layout-grid__cell--span-12 mdc-layout-grid__cell--span-6-desktop mdc-layout-grid__cell--span-4-tablet mdc-layout-grid__cell--span-4-mobile\">\n\t\t\t<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"telefon\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-tel\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Tel\u00e9fono\" value=\"\" type=\"tel\" name=\"telefon\" \/><\/span><br \/>\n\t\t\t\t\t\t<div style=\"display: none;\" class=\"cf7md-text-html\">\n\t\t\t\t<div class=\"mdc-textfield\" data-mdc-auto-init=\"MDCTextfield\">\n\t\t\t\t\t<label class=\"mdc-textfield__label\"><\/label>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\n<\/p>\n<p>\t\t<div class=\"cf7md-item cf7md-text mdc-layout-grid__cell mdc-layout-grid__cell--span-12 mdc-layout-grid__cell--span-6-desktop mdc-layout-grid__cell--span-4-tablet mdc-layout-grid__cell--span-4-mobile\">\n\t\t\t<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"entitat\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" placeholder=\"Entidad \/ Empresa\" value=\"\" type=\"text\" name=\"entitat\" \/><\/span><br \/>\n\t\t\t\t\t\t<div style=\"display: none;\" class=\"cf7md-text-html\">\n\t\t\t\t<div class=\"mdc-textfield\" data-mdc-auto-init=\"MDCTextfield\">\n\t\t\t\t\t<label class=\"mdc-textfield__label\"><\/label>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<br \/>\n\t\t<div class=\"cf7md-item cf7md-text mdc-layout-grid__cell mdc-layout-grid__cell--span-12 mdc-layout-grid__cell--span-6-desktop mdc-layout-grid__cell--span-4-tablet mdc-layout-grid__cell--span-4-mobile\">\n\t\t\t<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"cargo\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" placeholder=\"Cargo\" value=\"\" type=\"text\" name=\"cargo\" \/><\/span><br \/>\n\t\t\t\t\t\t<div style=\"display: none;\" class=\"cf7md-text-html\">\n\t\t\t\t<div class=\"mdc-textfield\" data-mdc-auto-init=\"MDCTextfield\">\n\t\t\t\t\t<label class=\"mdc-textfield__label\"><\/label>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\n<\/p>\n<p>\t\t<div class=\"cf7md-item cf7md-accept cf7md-is-wpcf7v5 mdc-layout-grid__cell mdc-layout-grid__cell--span-12 mdc-layout-grid__cell--span-12-desktop mdc-layout-grid__cell--span-8-tablet mdc-layout-grid__cell--span-4-mobile\">\n\t\t\t\t\t\t<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"acceptance-273\"><span class=\"wpcf7-form-control wpcf7-acceptance\"><span class=\"wpcf7-list-item\"><label><input type=\"checkbox\" name=\"acceptance-273\" value=\"1\" aria-invalid=\"false\" \/><span class=\"wpcf7-list-item-label\">He le\u00eddo y acepto la <a href=\"https:\/\/www.amicsdelpais.com\/es\/avis-legal\" title=\"Tratamiento de los Datos de Car\u00e1cter Personal\" target=\"_blank\">pol\u00edtica de privacidad (GDPR)<\/a>.<\/span><\/label><\/span><\/span><\/span><br \/>\n\t\t\t<label class=\"cf7md-accept-label\"><\/label>\n\t\t\t<div style=\"display: none;\" class=\"cf7md-checkbox-html\">\n\t\t\t\t<div class=\"mdc-checkbox__background\">\n\t\t\t\t\t<svg version=\"1.1\"\n\t\t\t\t\t\tclass=\"mdc-checkbox__checkmark\"\n\t\t\t\t\t\txmlns=\"http:\/\/www.w3.org\/2000\/svg\"\n\t\t\t\t\t\tviewBox=\"0 0 24 24\"\n\t\t\t\t\t\txml:space=\"preserve\">\n\t\t\t\t\t\t<path class=\"mdc-checkbox__checkmark__path\"\n\t\t\t\t\t\t\tfill=\"none\"\n\t\t\t\t\t\t\tstroke=\"white\"\n\t\t\t\t\t\t\td=\"M1.73,12.91 8.1,19.28 22.79,4.59\"\/>\n\t\t\t\t\t<\/svg>\n\t\t\t\t\t<div class=\"mdc-checkbox__mixedmark\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<br \/>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"\" type=\"hidden\" name=\"origen\" \/><br \/>\n\t\t<div class=\"cf7md-item cf7md-submit mdc-layout-grid__cell mdc-layout-grid__cell--span-12 mdc-layout-grid__cell--span-12-desktop mdc-layout-grid__cell--span-8-tablet mdc-layout-grid__cell--span-4-mobile\">\n\t\t\t<br \/>\n<input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Subscribirme\" \/><br \/>\n\t\t\t<svg class=\"cf7md-spinner\" width=\"25px\" height=\"25px\" viewBox=\"0 0 66 66\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n\t\t\t\t<circle class=\"cf7md-spinner-path\" fill=\"none\" stroke-width=\"6\" stroke-linecap=\"round\" cx=\"33\" cy=\"33\" r=\"30\"><\/circle>\n\t\t\t<\/svg>\n\t\t<\/div>\n\t\t<br \/>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n\n<\/div><\/div>\n\n<\/div><\/div>             <\/div>         <\/div>                   <style>.kadence-column15198_b55ca3-7f > .kt-inside-inner-col,.kadence-column15198_b55ca3-7f > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column15198_b55ca3-7f > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column15198_b55ca3-7f > .kt-inside-inner-col{flex-direction:column;}.kadence-column15198_b55ca3-7f > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column15198_b55ca3-7f > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column15198_b55ca3-7f{position:relative;}@media all and (max-width: 1024px){.kadence-column15198_b55ca3-7f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column15198_b55ca3-7f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>         <div class=\"wp-block-kadence-column kadence-column15198_b55ca3-7f\">             <div class=\"kt-inside-inner-col\">                                               <\/div>         <\/div>                  <\/div><\/div>                   <p class=\"wp-block-paragraph\"><\/p>         ","protected":false},"excerpt":{"rendered":"<p><b>Ramon Palacio<\/b>, enginiero y Vicepresidente del Cercle per al Coneixement, reflexiona sobre la crisis econ\u00f3mica actual y propone medidas econ\u00f3micas y sociales necesarias para poder salir de ella.<\/p>\n","protected":false},"author":22,"featured_media":19934,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"categories":[194,732,735,193],"tags":[],"class_list":["post-22228","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-articulos","category-cercle-per-al-coneixement-publicaciones","category-circulo-para-el-conocimiento-publicaciones","category-publicaciones"],"taxonomy_info":{"category":[{"value":194,"label":"Art\u00edculos"},{"value":732,"label":"Cercle per al Coneixement Publicaciones"},{"value":735,"label":"C\u00edrculo para el Conocimiento Publicaciones"},{"value":193,"label":"Publicaciones"}]},"featured_image_src_large":["https:\/\/www.amicsdelpais.com\/wp-content\/uploads\/2025\/07\/default_image_amics_del_pais-2.png",839,559,false],"author_info":{"display_name":"Ramon Palacio","author_link":"https:\/\/www.amicsdelpais.com\/es\/author\/ramon-palacio\/"},"comment_info":0,"category_info":[{"term_id":194,"name":"Art\u00edculos","slug":"articulos","term_group":0,"term_taxonomy_id":194,"taxonomy":"category","description":"","parent":193,"count":252,"filter":"raw","cat_ID":194,"category_count":252,"category_description":"","cat_name":"Art\u00edculos","category_nicename":"articulos","category_parent":193},{"term_id":732,"name":"Cercle per al Coneixement Publicaciones","slug":"cercle-per-al-coneixement-publicaciones","term_group":0,"term_taxonomy_id":732,"taxonomy":"category","description":"","parent":193,"count":1138,"filter":"raw","cat_ID":732,"category_count":1138,"category_description":"","cat_name":"Cercle per al Coneixement Publicaciones","category_nicename":"cercle-per-al-coneixement-publicaciones","category_parent":193},{"term_id":735,"name":"C\u00edrculo para el Conocimiento Publicaciones","slug":"circulo-para-el-conocimiento-publicaciones","term_group":0,"term_taxonomy_id":735,"taxonomy":"category","description":"","parent":771,"count":602,"filter":"raw","cat_ID":735,"category_count":602,"category_description":"","cat_name":"C\u00edrculo para el Conocimiento Publicaciones","category_nicename":"circulo-para-el-conocimiento-publicaciones","category_parent":771},{"term_id":193,"name":"Publicaciones","slug":"publicaciones","term_group":0,"term_taxonomy_id":193,"taxonomy":"category","description":"","parent":0,"count":761,"filter":"raw","cat_ID":193,"category_count":761,"category_description":"","cat_name":"Publicaciones","category_nicename":"publicaciones","category_parent":0}],"tag_info":false,"_links":{"self":[{"href":"https:\/\/www.amicsdelpais.com\/es\/wp-json\/wp\/v2\/posts\/22228","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.amicsdelpais.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.amicsdelpais.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.amicsdelpais.com\/es\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/www.amicsdelpais.com\/es\/wp-json\/wp\/v2\/comments?post=22228"}],"version-history":[{"count":0,"href":"https:\/\/www.amicsdelpais.com\/es\/wp-json\/wp\/v2\/posts\/22228\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.amicsdelpais.com\/es\/wp-json\/wp\/v2\/media\/19934"}],"wp:attachment":[{"href":"https:\/\/www.amicsdelpais.com\/es\/wp-json\/wp\/v2\/media?parent=22228"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.amicsdelpais.com\/es\/wp-json\/wp\/v2\/categories?post=22228"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.amicsdelpais.com\/es\/wp-json\/wp\/v2\/tags?post=22228"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}