{"id":21971,"date":"2006-04-14T00:00:00","date_gmt":"2006-04-13T22:00:00","guid":{"rendered":"https:\/\/new.barcelonatribuna.com\/el_fenomeno_match\/"},"modified":"2006-04-14T00:00:00","modified_gmt":"2006-04-13T22:00:00","slug":"el_fenomeno_match","status":"publish","type":"post","link":"https:\/\/www.amicsdelpais.com\/es\/el_fenomeno_match\/","title":{"rendered":"El fen\u00f3meno Match"},"content":{"rendered":"         <p class=\"link_ariadna\"><a href=\"https:\/\/www.amicsdelpais.com\/es\/publicaciones\">Publicaciones<\/a><\/p>                   <h1 class=\"wp-block-post-title\">El fen\u00f3meno Match<\/h1>          <style>.kb-row-layout-id15198_fd4370-d2 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id15198_fd4370-d2 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id15198_fd4370-d2 > .kt-row-column-wrap{column-gap:40px;row-gap:var(--global-kb-gap-md, 2rem);padding-top:0px;padding-bottom:24px;grid-template-columns:minmax(0, calc(70% - ((40px * 1 )\/2)))minmax(0, calc(30% - ((40px * 1 )\/2)));}.kb-row-layout-id15198_fd4370-d2 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id15198_fd4370-d2 > .kt-row-column-wrap{grid-template-columns:minmax(0, 2fr) minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id15198_fd4370-d2 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id15198_fd4370-d2 alignnone header_article_agenda wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-left-golden kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">         <style>.kadence-column15198_b1d053-1d > .kt-inside-inner-col,.kadence-column15198_b1d053-1d > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column15198_b1d053-1d > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column15198_b1d053-1d > .kt-inside-inner-col{flex-direction:column;}.kadence-column15198_b1d053-1d > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column15198_b1d053-1d > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column15198_b1d053-1d{position:relative;}@media all and (max-width: 1024px){.kadence-column15198_b1d053-1d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column15198_b1d053-1d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>         <div class=\"wp-block-kadence-column kadence-column15198_b1d053-1d\"><div class=\"kt-inside-inner-col\"><figure class=\"wp-block-post-featured-image\"><img loading=\"lazy\" decoding=\"async\" width=\"839\" height=\"559\" src=\"https:\/\/www.amicsdelpais.com\/wp-content\/uploads\/2025\/07\/default_image_amics_del_pais-2.png\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"\" style=\"object-fit:cover;\" srcset=\"https:\/\/www.amicsdelpais.com\/wp-content\/uploads\/2025\/07\/default_image_amics_del_pais-2.png 839w, https:\/\/www.amicsdelpais.com\/wp-content\/uploads\/2025\/07\/default_image_amics_del_pais-2-300x200.png 300w, https:\/\/www.amicsdelpais.com\/wp-content\/uploads\/2025\/07\/default_image_amics_del_pais-2-768x512.png 768w, https:\/\/www.amicsdelpais.com\/wp-content\/uploads\/2025\/07\/default_image_amics_del_pais-2-600x400.png 600w\" sizes=\"auto, (max-width: 839px) 100vw, 839px\" \/><\/figure><\/div><\/div>                   <style>.kadence-column15494_3829e6-92 > .kt-inside-inner-col,.kadence-column15494_3829e6-92 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column15494_3829e6-92 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column15494_3829e6-92 > .kt-inside-inner-col{flex-direction:column;}.kadence-column15494_3829e6-92 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column15494_3829e6-92 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column15494_3829e6-92{position:relative;}@media all and (max-width: 1024px){.kadence-column15494_3829e6-92 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column15494_3829e6-92 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>         <div class=\"wp-block-kadence-column kadence-column15494_3829e6-92\">             <div class=\"kt-inside-inner-col\">                                  <style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box14181_ae7a89-85 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box14181_ae7a89-85 .kt-blocks-info-box-link-wrap{border-top:0px solid var(u002du002dglobal-palette7, #eeeeee);border-right:0px solid var(u002du002dglobal-palette7, #eeeeee);border-bottom:1px solid #979797;border-left:0px solid var(u002du002dglobal-palette7, #eeeeee);border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:var(--global-palette1, #3182CE);padding-top:0px;padding-right:0px;padding-bottom:10px;padding-left:0px;margin-bottom:10px;}.kt-info-box14181_ae7a89-85 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box14181_ae7a89-85 .kt-info-svg-icon-flip, .kt-info-box14181_ae7a89-85 .kt-blocks-info-box-number{font-size:20px;}.kt-info-box14181_ae7a89-85 .kt-blocks-info-box-media{color:var(--global-palette4, #2D3748);border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:3px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:7px;margin-bottom:0px;margin-left:0px;}.kt-info-box14181_ae7a89-85 .kt-infobox-textcontent h6.kt-blocks-info-box-title{color:var(--global-palette4, #2D3748);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box14181_ae7a89-85 .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette4, #2D3748);}.kt-info-box14181_ae7a89-85 .kt-blocks-info-box-learnmore{background:transparent;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}@media all and (max-width: 1024px){.kt-info-box14181_ae7a89-85 .kt-blocks-info-box-link-wrap{border-top:0px solid var(u002du002dglobal-palette7, #eeeeee);border-right:0px solid var(u002du002dglobal-palette7, #eeeeee);border-bottom:1px solid #979797;border-left:0px solid var(u002du002dglobal-palette7, #eeeeee);}}@media all and (max-width: 767px){.kt-info-box14181_ae7a89-85 .kt-blocks-info-box-link-wrap{border-top:0px solid var(u002du002dglobal-palette7, #eeeeee);border-right:0px solid var(u002du002dglobal-palette7, #eeeeee);border-bottom:1px solid #979797;border-left:0px solid var(u002du002dglobal-palette7, #eeeeee);}}<\/style> <div class=\"wp-block-kadence-infobox kt-info-box14181_ae7a89-85 info_block_01\">     <span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-left kt-info-halign-left kb-info-box-vertical-media-align-top\">         <div class=\"kt-blocks-info-box-media-container\">             <div class=\"kt-blocks-info-box-media kt-info-media-animate-none\">                 <div class=\"kadence-info-box-icon-container kt-info-icon-animate-none\">                     <div class=\"kadence-info-box-icon-inner-container\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_book kt-info-svg-icon\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  role=\"img\"><title>Hora<\/title><path d=\"M4 19.5A2.5 2.5 0 0 1 6.5 17H20\"\/><path d=\"M6.5 2H20v20H6.5A2.5 2.5 0 0 1 4 19.5v-15A2.5 2.5 0 0 1 6.5 2z\"\/><\/svg><\/span><\/div>                 <\/div>             <\/div>         <\/div>         <div class=\"kt-infobox-textcontent\">             <h6 class=\"kt-blocks-info-box-title\">Tipo de publicaci\u00f3n<\/h6><p class=\"kt-blocks-info-box-text\"><a href=\"\/publicacions\/articulos\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Art\u00edculos<\/a><\/p>        <\/div>     <\/span> <\/div>                  <style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box15198_70ed2d-ec .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box15198_70ed2d-ec .kt-blocks-info-box-link-wrap{border-top:0px solid var(u002du002dglobal-palette7, #eeeeee);border-right:0px solid var(u002du002dglobal-palette7, #eeeeee);border-bottom:0px solid #979797;border-left:0px solid var(u002du002dglobal-palette7, #eeeeee);border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:var(--global-palette1, #3182CE);padding-top:0px;padding-right:0px;padding-bottom:10px;padding-left:0px;}.kt-info-box15198_70ed2d-ec .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box15198_70ed2d-ec .kt-info-svg-icon-flip, .kt-info-box15198_70ed2d-ec .kt-blocks-info-box-number{font-size:20px;}.kt-info-box15198_70ed2d-ec .kt-blocks-info-box-media{color:var(--global-palette4, #2D3748);border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:3px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:7px;margin-bottom:0px;margin-left:0px;}.kt-info-box15198_70ed2d-ec .kt-infobox-textcontent h6.kt-blocks-info-box-title{color:var(--global-palette4, #2D3748);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box15198_70ed2d-ec .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette4, #2D3748);}.kt-info-box15198_70ed2d-ec .kt-blocks-info-box-learnmore{background:transparent;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}@media all and (max-width: 1024px){.kt-info-box15198_70ed2d-ec .kt-blocks-info-box-link-wrap{border-top:0px solid var(u002du002dglobal-palette7, #eeeeee);border-right:0px solid var(u002du002dglobal-palette7, #eeeeee);border-bottom:0px solid #979797;border-left:0px solid var(u002du002dglobal-palette7, #eeeeee);}}@media all and (max-width: 767px){.kt-info-box15198_70ed2d-ec .kt-blocks-info-box-link-wrap{border-top:0px solid var(u002du002dglobal-palette7, #eeeeee);border-right:0px solid var(u002du002dglobal-palette7, #eeeeee);border-bottom:0px solid #979797;border-left:0px solid var(u002du002dglobal-palette7, #eeeeee);}}<\/style> <div class=\"wp-block-kadence-infobox kt-info-box15198_70ed2d-ec info_block_01\">     <span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-left kt-info-halign-left kb-info-box-vertical-media-align-top\">         <div class=\"kt-blocks-info-box-media-container\">             <div class=\"kt-blocks-info-box-media kt-info-media-animate-none\">                 <div class=\"kadence-info-box-icon-container kt-info-icon-animate-none\">                     <div class=\"kadence-info-box-icon-inner-container\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_calendar kt-info-svg-icon\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  role=\"img\"><title>Hora<\/title><rect x=\"3\" y=\"4\" width=\"18\" height=\"18\" rx=\"2\" ry=\"2\"\/><line x1=\"16\" y1=\"2\" x2=\"16\" y2=\"6\"\/><line x1=\"8\" y1=\"2\" x2=\"8\" y2=\"6\"\/><line x1=\"3\" y1=\"10\" x2=\"21\" y2=\"10\"\/><\/svg><\/span><\/div>                 <\/div>             <\/div>         <\/div>         <div class=\"kt-infobox-textcontent\">             <h6 class=\"kt-blocks-info-box-title\">Data<\/h6>             <p class=\"kt-blocks-info-box-text\">14-04-2006<\/p>         <\/div>     <\/span> <\/div>              <\/div>                      <\/div>                    <\/div><\/div>          <style>.kb-row-layout-id15198_57c2d8-c9 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id15198_57c2d8-c9 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id15198_57c2d8-c9 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, calc(70% - ((var(--global-kb-gap-md, 2rem) * 1 )\/2)))minmax(0, calc(30% - ((var(--global-kb-gap-md, 2rem) * 1 )\/2)));}.kb-row-layout-id15198_57c2d8-c9 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id15198_57c2d8-c9 > .kt-row-column-wrap{grid-template-columns:minmax(0, 2fr) minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id15198_57c2d8-c9 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id15198_57c2d8-c9 alignnone content_article_agenda wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-left-golden kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">         <style>.kadence-column15198_459565-82 > .kt-inside-inner-col,.kadence-column15198_459565-82 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column15198_459565-82 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column15198_459565-82 > .kt-inside-inner-col{flex-direction:column;}.kadence-column15198_459565-82 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column15198_459565-82 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column15198_459565-82{position:relative;}@media all and (max-width: 1024px){.kadence-column15198_459565-82 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column15198_459565-82 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>         <div class=\"wp-block-kadence-column kadence-column15198_459565-82\">             <div class=\"kt-inside-inner-col\">             <div class=\"autor_post wp-block-post-author-name\"><a href=\"https:\/\/www.amicsdelpais.com\/es\/author\/jmayans\/\" target=\"_blank\" class=\"wp-block-post-author-name__link\">Joan Mayans Planells<\/a><\/div>             <div class=\"summary_post wp-block-post-excerpt\"><p class=\"wp-block-post-excerpt__excerpt\">Millones de personas buscando su media naranja en internet. Millones de usuarios de los portales de contactos. Millones de euros de beneficios de estas empresas. Millones de lecturas a un peque\u00f1o revuelo medi\u00e1tico que parece tener como fin \u00faltimo legitimarse a s\u00ed mismo, o lo que es lo mismo, normalizar por el camino del titular&hellip; <\/p><\/div>                           <b>Sobre los n\u00fameros<\/b> Diversas fuentes y estudios est\u00e1n hablando de m\u00e1s de dos millones y medio de usuarios de portales de contactos en Internet y analizan el auge de este tipo de portales que vienen a sustituir o evolucionar el trabajo de celestineo de las <i>tradicionales<\/i> agencias matrimoniales, s\u00f3lo que a <b>formato digital<\/b>, <b>escala global<\/b> y benefici\u00e1ndose de todas aquellos factores que generalmente caracterizan las <b>relaciones cibersociales<\/b>. A saber, un r\u00e9gimen inicial de relativo anonimato (m\u00e1s bien, <i>pseudonimato<\/i>), las consabidas ventajas de comodidad del consumo desde la casa de cada uno, etc.  Los datos de los mencionados estudios llegan a hablarnos, en algunos casos, de cinco millones de ciudadanos espa\u00f1oles buscando pareja en internet, lo que ser\u00eda un porcentaje muy sustancioso de esos siete millones de <i>singles<\/i> que se cuentan en el Estado Espa\u00f1ol. Otros datos probablemente m\u00e1s fiables hablan de m\u00e1s de dos millones y medio de usuarios de este tipo de portales, siguiendo un estudio publicado recientemente por la consultora Nielsen\/\/Netratings.   Por otro lado, otras cifras a tener en cuenta para intentar evaluar realmente las dimensiones de esta historia son los dos millones y medio de <b><i>usuarios registrados<\/i><\/b> en una de las empresas l\u00edderes en el sector. Con todo lo que implica el concepto de \u201cusuario registrado\u201d. Sin que sea una cifra p\u00fablica ni oficial, desde esta empresa se maneja un porcentaje de un 6% de <i>clientes reales<\/i>. Sin ser un <i>ratio<\/i> muy alto, s\u00ed que es cierto que sigue trat\u00e1ndose de un <i>mont\u00f3n de personas<\/i>. No son millones de clientes, pero s\u00ed un negocio que se atisba enorme. A poco que vaya consolid\u00e1ndose como tal, a poco que su consumo se vaya <i>normalizando<\/i> y convirtiendo en <i>social<\/i> y <i>moralmente<\/i> respetable.   <b>Sobre la percepci\u00f3n moral del producto<\/b> Estas \u00faltimas referencias son interesantes. Hablando con usuarios no s\u00f3lo de portales de contactos, sino todo tipo de entornos cibersociales, es frecuente detectar la percepci\u00f3n de una cierta descalificaci\u00f3n inicial sobre las relaciones de pareja que tienen su origen en Internet. Como si quien busca pareja en internet lo hace porque no sabe hacerlo <i>fuera<\/i>, como si quien encuentra pareja en internet se estuviera dejando enga\u00f1ar, como si, en definitiva, se trata de relaciones que socialmente no son aceptadas a la primera.   Esta percepci\u00f3n, probablemente menguante, no debe ser especialmente alarmante. No deja de ser previsible que una nueva forma de hacer cualquier cosa no reciba, durante un tiempo, el mismo valor o prestigio que <i>la vieja manera de hacer las cosas<\/i>. Sin embargo, s\u00ed que nos indica que actualmente existe una cierta sanci\u00f3n moral que afecta a este tipo de relaciones. Aunque se est\u00e9 diluyendo, no hay duda de que esto es un obst\u00e1culo para aquellos cuyo negocio est\u00e1, precisamente, en aquello moralmente reprobado. No es nada extra\u00f1o, pues, que uno de los objetivos de los portales y las empresas de contactos en Internet sea acelerar al m\u00e1ximo el proceso de <i>normalizaci\u00f3n<\/i> y <i>respetabilizaci\u00f3n<\/i> de su producto.   <b>Sobre la campa\u00f1a publicitaria en televisi\u00f3n<\/b> Otro factor que ha entrado en juego en las \u00faltimas semanas, al menos en las cadenas de televisi\u00f3n de \u00e1mbito estatal del Estado Espa\u00f1ol, es la importante campa\u00f1a de publicidad que ha puesto en marcha una de las empresas l\u00edderes del sector, <b>match.com<\/b>. No creo que sea del todo casual que la publicaci\u00f3n de los citados estudios magnificando (num\u00e9ricamente) el fen\u00f3meno, la campa\u00f1a de publicidad televisiva de esta empresa y el <i>rebufo medi\u00e1tico<\/i> y noticioso que se ha producido alrededor haya ocurrido todo en un margen tan escaso de tiempo. Que todo ello tenga lugar alrededor de la fecha de San Valent\u00edn tampoco creo que sea accidental.   La campa\u00f1a publicitaria en s\u00ed misma tambi\u00e9n merece una mirada atenta. Simplificando mucho, podr\u00edamos decir que hay dos grandes tipos de anuncios televisivos: <b><i>los que explican el producto<\/i><\/b>, cuya estrategia es venderlo d\u00e1ndolo a conocer, mostrando sus caracter\u00edsticas y ventajas; y <b><i>los que explican lo que ocurre cuando uno tiene el producto<\/i><\/b>, que se dedican a mostrar cu\u00e1n estupendo es todo cuando se ha adquirido aquello que se vende. Continuando con la simplificaci\u00f3n: un anuncio de detergente suele funcionar del primer modo, mientras que los de perfumes casi siempre lo hacen de la segunda.   La campa\u00f1a de <i>match.com<\/i> ha optado por el segundo camino, escenificando una serie de situaciones en las que aquello que vende este portal de contactos ha intervenido. Se trata de tres anuncios cuyas l\u00edneas argumentales nos proyectan peque\u00f1os momentos de lo que, idealmente, podr\u00eda ser una relaci\u00f3n de pareja en estado de <i>enamoramiento<\/i>. Muy brevemente, son, a) un se\u00f1or disfrazado, y rodeado de globos esperando a su pareja en el piso de ella; b) una pareja podando el seto de su jard\u00edn y recortando en \u00e9l una silueta de ambos, cogidos de la mano; y c) una pareja durmiendo, \u00e9l se va a trabajar y, como es repartidor de pescado, deja en su lugar, en la cama, un enorme pez en su lugar. En todos los anuncios de la campa\u00f1a, el mensaje, el tratamiento visual colorido y casi <i>kitsch<\/i>, la m\u00fasica de fondo, la ausencia de voces durante la mayor parte del mismo, nos muestran una mini-pel\u00edcula de veinte segundos, una peque\u00f1a <b><i>comedia rom\u00e1ntica<\/i><\/b> de la que, dice la campa\u00f1a, <b>podemos ser protagonistas<\/b>.   Este es, para m\u00ed, el tema fundamental de la campa\u00f1a y lo que la hace m\u00e1s interesante para este peque\u00f1o art\u00edculo: los anuncios nos acercan unas situaciones que nos son tremendamente familiares, porque las hemos visto en varios centenares de pel\u00edculas. El producto que <i>a trav\u00e9s de internet<\/i> y <i>s\u00f3lo en internet<\/i> nos ofrecen los portales de contactos no es una suscripci\u00f3n a un servicio online donde <b>no hay un producto final genuino<\/b> (el cliente y el producto <b>son exactamente lo mismo<\/b>) sino la posibilidad de protagonizar, en primera persona, esa pel\u00edcula que hemos visto cientos de veces.   <b>Concluyendo&#8230; <\/b> As\u00ed pues, recapitulando e identificando el contexto, el decorado y los protagonistas de esta peque\u00f1a historia, tenemos: <ol type=\"A\"> <li><b>El momento. <\/b>La historia se sit\u00faan en la combinaci\u00f3n de dos momentos o situaciones, de distinto ciclo: una situaci\u00f3n temporal de ciclo largo: el comercio electr\u00f3nico cada vez tiene m\u00e1s aceptaci\u00f3n y goza de mayor confianza como forma de adquirir bienes y servicios. Ya no es tan raro y, desde luego, no parece tan peligroso, comprar a trav\u00e9s de internet. Por otro lado, estamos en un momento concreto del ciclo anual, especialmente interesante a nivel comercial: los aleda\u00f1os de San Valent\u00edn  <li><b>El decorado: <\/b>un campo de negocio de unas dimensiones muy importantes y con un margen de crecimiento econ\u00f3mico enorme, que despu\u00e9s de varios a\u00f1os de maduraci\u00f3n del medio (Internet como v\u00eda para conocer gente) y de \u00e9xito en diversos pa\u00edses, se destapa con fuerza en el Estado Espa\u00f1ol.   <li><b>Los protagonistas<\/b>: estudios y cifras de consultoras internacionales de gran prestigio que dicen que el fen\u00f3meno est\u00e1 mucho <b>m\u00e1s extendido de lo que imagin\u00e1bamos<\/b>; noticias reproducidas en varios medios de comunicaci\u00f3n repitiendo y coreando estos estudios y cifras, dici\u00e9ndonos que es mucho <b>m\u00e1s relevante de lo que cre\u00edamos<\/b>; una campa\u00f1a de publicidad a gran escala que nos ense\u00f1a que, adem\u00e1s, se trata de algo mucho <b>m\u00e1s normal (y divertido) de lo que nos parec\u00eda<\/b>.  <\/ol> Si observamos el dibujo completo, la sucesi\u00f3n de los peque\u00f1os eslabones, aparentemente inconexos, de esta cadena, resulta que nos encontramos con una campa\u00f1a publicitaria que se convierte en noticia que se convierte de nuevo en campa\u00f1a publicitaria. El efecto producido por esta combinaci\u00f3n de situaci\u00f3n, decorado y protagonistas es, precisamente, el mismo que intenta transmitir la propia campa\u00f1a publicitaria: los portales de contactos en internet son algo <i>perfectamente normal<\/i>, perfectamente <i>asequible<\/i>, perfectamente encajado dentro de nuestra moral colectiva te\u00f1ida hegem\u00f3nicamente de colores, sabores y decires <i>jolibudescos<\/i>.   En realidad, mirada con una cierta distancia, la pel\u00edcula no resulta especialmente sorprendente. Ni siquiera objetivamente censurable. Tan s\u00f3lo me deja un regusto un poco amargo el pensar que lo que estos <b>portales privados<\/b>, tecnol\u00f3gicamente cerrados, altamente monitorizados en su funcionamiento y mediatizados completamente por una transacci\u00f3n comercial vengan a ocupar el lugar de otros entornos y espacios en internet, de <b>car\u00e1cter p\u00fablico<\/b>, donde todo lo que pasa en un portal de contactos, tambi\u00e9n <i>pod\u00eda pasar<\/i>, pero lo que es m\u00e1s interesante, <i>pod\u00eda <b>no<\/b> pasar<\/i>.   Quiz\u00e1 lo que ocurre con los portales de contactos es que, como las comedias rom\u00e1nticas, sabemos perfectamente como acabar\u00e1n y podemos predecir la mayor\u00eda de sus giros argumentales y motivaciones de sus protagonistas. Del mismo modo, los portales de contactos, en su intento de ofrecer un producto concreto y perceptible, merecedor de una transacci\u00f3n econ\u00f3mica, pierden por el camino la combinaci\u00f3n de incertidumbres e inc\u00f3gnitas que presidir\u00eda una interacci\u00f3n similar no mediatizada, en el espacio p\u00fablico. En su elaboraci\u00f3n del producto rom\u00e1ntico, el portal de contactos sacrifica una parte del propio romanticismo, enlat\u00e1ndolo y envas\u00e1ndolo para su consumo. Por otro lado, \u00bfqu\u00e9 otra cosa podemos esperar de estos tiempos nuestros tan <i>polipropilenizados<\/i>?   <b>&#8212;&#8212;-<\/b> Aquest article s&#8217;ha publicat alhora aqu\u00ed, com a reflexi\u00f3 del Cercle, i a l&#8217;Observatori per a la CiberSocietat (<a target=\"_new\" href=\"http:\/\/www.cibersociedad.net\" rel=\"noopener\">http:\/\/www.cibersociedad.net<\/a>) com a Article de Divulgaci\u00f3.                                          <style>.kb-row-layout-id22850_b19245-db > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id22850_b19245-db > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id22850_b19245-db > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:24px;padding-bottom:0px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id22850_b19245-db{background-color:#fecc8c;background-image:url('https:\/\/www.amicsdelpais.com\/wp-content\/uploads\/2025\/06\/bg_newsletter_01.svg');background-size:auto;background-position:100% 0%;background-attachment:scroll;background-repeat:repeat-y;}.kb-row-layout-id22850_b19245-db > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id22850_b19245-db > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id22850_b19245-db > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id22850_b19245-db alignnone kt-row-has-bg block_newsletter wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column22850_a01aca-24 > .kt-inside-inner-col{padding-bottom:0px;}.kadence-column22850_a01aca-24 > .kt-inside-inner-col,.kadence-column22850_a01aca-24 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column22850_a01aca-24 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column22850_a01aca-24 > .kt-inside-inner-col{flex-direction:column;}.kadence-column22850_a01aca-24 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column22850_a01aca-24 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column22850_a01aca-24{position:relative;}@media all and (max-width: 1024px){.kadence-column22850_a01aca-24 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column22850_a01aca-24 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column22850_a01aca-24\"><div class=\"kt-inside-inner-col\">\n<h2 class=\"wp-block-heading\">Suscr\u00edbete al newsletter<\/h2>\n\n\n\n<p>Suscr\u00edbete al <strong>Newsletter de Amics del Pa\u00eds<\/strong> para estar al d\u00eda de todo lo que hacemos. Recibir\u00e1s informaci\u00f3n sobre nuestras actividades, noticias destacadas y las convocatorias y novedades de las conferencias que organizamos.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f42828-o1\" lang=\"es-ES\" dir=\"ltr\" data-wpcf7-id=\"42828\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/es\/wp-json\/wp\/v2\/posts\/21971#wpcf7-f42828-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Formulario de contacto\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"42828\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.5\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"es_ES\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f42828-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<p>\t\t<div id=\"cf7md-form\" class=\"cf7md-form cf7md-spacing--tight\">\n\t\t\t<div class=\"mdc-layout-grid\">\n\t\t\t\t\t\t\t\t\n<\/p>\n<p>\t\t<div class=\"cf7md-item cf7md-text mdc-layout-grid__cell mdc-layout-grid__cell--span-12 mdc-layout-grid__cell--span-6-desktop mdc-layout-grid__cell--span-4-tablet mdc-layout-grid__cell--span-4-mobile\">\n\t\t\t<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"nom\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Nombre\" value=\"\" type=\"text\" name=\"nom\" \/><\/span><br \/>\n\t\t\t\t\t\t<div style=\"display: none;\" class=\"cf7md-text-html\">\n\t\t\t\t<div class=\"mdc-textfield\" data-mdc-auto-init=\"MDCTextfield\">\n\t\t\t\t\t<label class=\"mdc-textfield__label\"><\/label>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<br \/>\n\t\t<div class=\"cf7md-item cf7md-text mdc-layout-grid__cell mdc-layout-grid__cell--span-12 mdc-layout-grid__cell--span-6-desktop mdc-layout-grid__cell--span-4-tablet mdc-layout-grid__cell--span-4-mobile\">\n\t\t\t<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"cognoms\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Apellidos\" value=\"\" type=\"text\" name=\"cognoms\" \/><\/span><br \/>\n\t\t\t\t\t\t<div style=\"display: none;\" class=\"cf7md-text-html\">\n\t\t\t\t<div class=\"mdc-textfield\" data-mdc-auto-init=\"MDCTextfield\">\n\t\t\t\t\t<label class=\"mdc-textfield__label\"><\/label>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\n<\/p>\n<p>\t\t<div class=\"cf7md-item cf7md-text mdc-layout-grid__cell mdc-layout-grid__cell--span-12 mdc-layout-grid__cell--span-6-desktop mdc-layout-grid__cell--span-4-tablet mdc-layout-grid__cell--span-4-mobile\">\n\t\t\t<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Correo electr\u00f3nico\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span><br \/>\n\t\t\t\t\t\t<div style=\"display: none;\" class=\"cf7md-text-html\">\n\t\t\t\t<div class=\"mdc-textfield\" data-mdc-auto-init=\"MDCTextfield\">\n\t\t\t\t\t<label class=\"mdc-textfield__label\"><\/label>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<br \/>\n\t\t<div class=\"cf7md-item cf7md-text mdc-layout-grid__cell mdc-layout-grid__cell--span-12 mdc-layout-grid__cell--span-6-desktop mdc-layout-grid__cell--span-4-tablet mdc-layout-grid__cell--span-4-mobile\">\n\t\t\t<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"telefon\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-tel\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Tel\u00e9fono\" value=\"\" type=\"tel\" name=\"telefon\" \/><\/span><br \/>\n\t\t\t\t\t\t<div style=\"display: none;\" class=\"cf7md-text-html\">\n\t\t\t\t<div class=\"mdc-textfield\" data-mdc-auto-init=\"MDCTextfield\">\n\t\t\t\t\t<label class=\"mdc-textfield__label\"><\/label>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\n<\/p>\n<p>\t\t<div class=\"cf7md-item cf7md-text mdc-layout-grid__cell mdc-layout-grid__cell--span-12 mdc-layout-grid__cell--span-6-desktop mdc-layout-grid__cell--span-4-tablet mdc-layout-grid__cell--span-4-mobile\">\n\t\t\t<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"entitat\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" placeholder=\"Entidad \/ Empresa\" value=\"\" type=\"text\" name=\"entitat\" \/><\/span><br \/>\n\t\t\t\t\t\t<div style=\"display: none;\" class=\"cf7md-text-html\">\n\t\t\t\t<div class=\"mdc-textfield\" data-mdc-auto-init=\"MDCTextfield\">\n\t\t\t\t\t<label class=\"mdc-textfield__label\"><\/label>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<br \/>\n\t\t<div class=\"cf7md-item cf7md-text mdc-layout-grid__cell mdc-layout-grid__cell--span-12 mdc-layout-grid__cell--span-6-desktop mdc-layout-grid__cell--span-4-tablet mdc-layout-grid__cell--span-4-mobile\">\n\t\t\t<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"cargo\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" placeholder=\"Cargo\" value=\"\" type=\"text\" name=\"cargo\" \/><\/span><br \/>\n\t\t\t\t\t\t<div style=\"display: none;\" class=\"cf7md-text-html\">\n\t\t\t\t<div class=\"mdc-textfield\" data-mdc-auto-init=\"MDCTextfield\">\n\t\t\t\t\t<label class=\"mdc-textfield__label\"><\/label>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\n<\/p>\n<p>\t\t<div class=\"cf7md-item cf7md-accept cf7md-is-wpcf7v5 mdc-layout-grid__cell mdc-layout-grid__cell--span-12 mdc-layout-grid__cell--span-12-desktop mdc-layout-grid__cell--span-8-tablet mdc-layout-grid__cell--span-4-mobile\">\n\t\t\t\t\t\t<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"acceptance-273\"><span class=\"wpcf7-form-control wpcf7-acceptance\"><span class=\"wpcf7-list-item\"><label><input type=\"checkbox\" name=\"acceptance-273\" value=\"1\" aria-invalid=\"false\" \/><span class=\"wpcf7-list-item-label\">He le\u00eddo y acepto la <a href=\"https:\/\/www.amicsdelpais.com\/es\/avis-legal\" title=\"Tratamiento de los Datos de Car\u00e1cter Personal\" target=\"_blank\">pol\u00edtica de privacidad (GDPR)<\/a>.<\/span><\/label><\/span><\/span><\/span><br \/>\n\t\t\t<label class=\"cf7md-accept-label\"><\/label>\n\t\t\t<div style=\"display: none;\" class=\"cf7md-checkbox-html\">\n\t\t\t\t<div class=\"mdc-checkbox__background\">\n\t\t\t\t\t<svg version=\"1.1\"\n\t\t\t\t\t\tclass=\"mdc-checkbox__checkmark\"\n\t\t\t\t\t\txmlns=\"http:\/\/www.w3.org\/2000\/svg\"\n\t\t\t\t\t\tviewBox=\"0 0 24 24\"\n\t\t\t\t\t\txml:space=\"preserve\">\n\t\t\t\t\t\t<path class=\"mdc-checkbox__checkmark__path\"\n\t\t\t\t\t\t\tfill=\"none\"\n\t\t\t\t\t\t\tstroke=\"white\"\n\t\t\t\t\t\t\td=\"M1.73,12.91 8.1,19.28 22.79,4.59\"\/>\n\t\t\t\t\t<\/svg>\n\t\t\t\t\t<div class=\"mdc-checkbox__mixedmark\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<br \/>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"\" type=\"hidden\" name=\"origen\" \/><br \/>\n\t\t<div class=\"cf7md-item cf7md-submit mdc-layout-grid__cell mdc-layout-grid__cell--span-12 mdc-layout-grid__cell--span-12-desktop mdc-layout-grid__cell--span-8-tablet mdc-layout-grid__cell--span-4-mobile\">\n\t\t\t<br \/>\n<input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Subscribirme\" \/><br \/>\n\t\t\t<svg class=\"cf7md-spinner\" width=\"25px\" height=\"25px\" viewBox=\"0 0 66 66\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n\t\t\t\t<circle class=\"cf7md-spinner-path\" fill=\"none\" stroke-width=\"6\" stroke-linecap=\"round\" cx=\"33\" cy=\"33\" r=\"30\"><\/circle>\n\t\t\t<\/svg>\n\t\t<\/div>\n\t\t<br \/>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n\n<\/div><\/div>\n\n<\/div><\/div>             <\/div>         <\/div>                   <style>.kadence-column15198_b55ca3-7f > .kt-inside-inner-col,.kadence-column15198_b55ca3-7f > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column15198_b55ca3-7f > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column15198_b55ca3-7f > .kt-inside-inner-col{flex-direction:column;}.kadence-column15198_b55ca3-7f > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column15198_b55ca3-7f > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column15198_b55ca3-7f{position:relative;}@media all and (max-width: 1024px){.kadence-column15198_b55ca3-7f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column15198_b55ca3-7f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>         <div class=\"wp-block-kadence-column kadence-column15198_b55ca3-7f\">             <div class=\"kt-inside-inner-col\">                                               <\/div>         <\/div>                  <\/div><\/div>                   <p><\/p>         ","protected":false},"excerpt":{"rendered":"<p>Millones de personas buscando su media naranja en internet. Millones de usuarios de los portales de contactos. Millones de euros de beneficios de estas empresas. Millones de lecturas a un peque\u00f1o revuelo medi\u00e1tico que parece tener como fin \u00faltimo legitimarse a s\u00ed mismo, o lo que es lo mismo, <i>normalizar<\/i> por el camino del titular masivo, una pr\u00e1ctica que, es verdad, no deber\u00eda tener nada de <i>raro<\/i>. Pero tanto mill\u00f3n me inquieta un poco, as\u00ed que he querido poner en orden algunas de estas inquietudes, a ver si les encuentro una l\u00ednea argumental&#8230;<\/p>\n","protected":false},"author":26,"featured_media":19934,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"categories":[194,732,735,193],"tags":[],"class_list":["post-21971","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-articulos","category-cercle-per-al-coneixement-publicaciones","category-circulo-para-el-conocimiento-publicaciones","category-publicaciones"],"taxonomy_info":{"category":[{"value":194,"label":"Art\u00edculos"},{"value":732,"label":"Cercle per al Coneixement Publicaciones"},{"value":735,"label":"C\u00edrculo para el Conocimiento Publicaciones"},{"value":193,"label":"Publicaciones"}]},"featured_image_src_large":["https:\/\/www.amicsdelpais.com\/wp-content\/uploads\/2025\/07\/default_image_amics_del_pais-2.png",839,559,false],"author_info":{"display_name":"Joan Mayans Planells","author_link":"https:\/\/www.amicsdelpais.com\/es\/author\/jmayans\/"},"comment_info":0,"category_info":[{"term_id":194,"name":"Art\u00edculos","slug":"articulos","term_group":0,"term_taxonomy_id":194,"taxonomy":"category","description":"","parent":193,"count":252,"filter":"raw","cat_ID":194,"category_count":252,"category_description":"","cat_name":"Art\u00edculos","category_nicename":"articulos","category_parent":193},{"term_id":732,"name":"Cercle per al Coneixement Publicaciones","slug":"cercle-per-al-coneixement-publicaciones","term_group":0,"term_taxonomy_id":732,"taxonomy":"category","description":"","parent":193,"count":1138,"filter":"raw","cat_ID":732,"category_count":1138,"category_description":"","cat_name":"Cercle per al Coneixement Publicaciones","category_nicename":"cercle-per-al-coneixement-publicaciones","category_parent":193},{"term_id":735,"name":"C\u00edrculo para el Conocimiento Publicaciones","slug":"circulo-para-el-conocimiento-publicaciones","term_group":0,"term_taxonomy_id":735,"taxonomy":"category","description":"","parent":771,"count":602,"filter":"raw","cat_ID":735,"category_count":602,"category_description":"","cat_name":"C\u00edrculo para el Conocimiento Publicaciones","category_nicename":"circulo-para-el-conocimiento-publicaciones","category_parent":771},{"term_id":193,"name":"Publicaciones","slug":"publicaciones","term_group":0,"term_taxonomy_id":193,"taxonomy":"category","description":"","parent":0,"count":761,"filter":"raw","cat_ID":193,"category_count":761,"category_description":"","cat_name":"Publicaciones","category_nicename":"publicaciones","category_parent":0}],"tag_info":false,"_links":{"self":[{"href":"https:\/\/www.amicsdelpais.com\/es\/wp-json\/wp\/v2\/posts\/21971","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.amicsdelpais.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.amicsdelpais.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.amicsdelpais.com\/es\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.amicsdelpais.com\/es\/wp-json\/wp\/v2\/comments?post=21971"}],"version-history":[{"count":0,"href":"https:\/\/www.amicsdelpais.com\/es\/wp-json\/wp\/v2\/posts\/21971\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.amicsdelpais.com\/es\/wp-json\/wp\/v2\/media\/19934"}],"wp:attachment":[{"href":"https:\/\/www.amicsdelpais.com\/es\/wp-json\/wp\/v2\/media?parent=21971"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.amicsdelpais.com\/es\/wp-json\/wp\/v2\/categories?post=21971"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.amicsdelpais.com\/es\/wp-json\/wp\/v2\/tags?post=21971"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}