{"id":21699,"date":"2006-11-24T00:00:00","date_gmt":"2006-11-23T23:00:00","guid":{"rendered":"https:\/\/new.barcelonatribuna.com\/resumen_de_la_cenadebate_con_isabel_aguilera\/"},"modified":"2006-11-24T00:00:00","modified_gmt":"2006-11-23T23:00:00","slug":"resumen_de_la_cenadebate_con_isabel_aguilera","status":"publish","type":"post","link":"https:\/\/www.amicsdelpais.com\/es\/resumen_de_la_cenadebate_con_isabel_aguilera\/","title":{"rendered":"Resumen de la cena-debate con Isabel Aguilera"},"content":{"rendered":"         <p class=\"link_ariadna\"><a href=\"https:\/\/www.amicsdelpais.com\/es\/publicaciones\">Publicaciones<\/a><\/p>                   <h1 class=\"wp-block-post-title\">Resumen de la cena-debate con Isabel Aguilera<\/h1>          <style>.kb-row-layout-id15198_fd4370-d2 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id15198_fd4370-d2 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id15198_fd4370-d2 > .kt-row-column-wrap{column-gap:40px;row-gap:var(--global-kb-gap-md, 2rem);padding-top:0px;padding-bottom:24px;grid-template-columns:minmax(0, calc(70% - ((40px * 1 )\/2)))minmax(0, calc(30% - ((40px * 1 )\/2)));}.kb-row-layout-id15198_fd4370-d2 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id15198_fd4370-d2 > .kt-row-column-wrap{grid-template-columns:minmax(0, 2fr) minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id15198_fd4370-d2 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id15198_fd4370-d2 alignnone header_article_agenda wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-left-golden kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">         <style>.kadence-column15198_b1d053-1d > .kt-inside-inner-col,.kadence-column15198_b1d053-1d > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column15198_b1d053-1d > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column15198_b1d053-1d > .kt-inside-inner-col{flex-direction:column;}.kadence-column15198_b1d053-1d > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column15198_b1d053-1d > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column15198_b1d053-1d{position:relative;}@media all and (max-width: 1024px){.kadence-column15198_b1d053-1d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column15198_b1d053-1d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>         <div class=\"wp-block-kadence-column kadence-column15198_b1d053-1d\"><div class=\"kt-inside-inner-col\"><figure class=\"wp-block-post-featured-image\"><img loading=\"lazy\" decoding=\"async\" width=\"235\" height=\"271\" src=\"https:\/\/www.amicsdelpais.com\/wp-content\/uploads\/2025\/07\/art_176_2g2c.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"\" style=\"object-fit:cover;\" \/><\/figure><\/div><\/div>                   <style>.kadence-column15494_3829e6-92 > .kt-inside-inner-col,.kadence-column15494_3829e6-92 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column15494_3829e6-92 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column15494_3829e6-92 > .kt-inside-inner-col{flex-direction:column;}.kadence-column15494_3829e6-92 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column15494_3829e6-92 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column15494_3829e6-92{position:relative;}@media all and (max-width: 1024px){.kadence-column15494_3829e6-92 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column15494_3829e6-92 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>         <div class=\"wp-block-kadence-column kadence-column15494_3829e6-92\">             <div class=\"kt-inside-inner-col\">                                  <style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box14181_ae7a89-85 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box14181_ae7a89-85 .kt-blocks-info-box-link-wrap{border-top:0px solid var(u002du002dglobal-palette7, #eeeeee);border-right:0px solid var(u002du002dglobal-palette7, #eeeeee);border-bottom:1px solid #979797;border-left:0px solid var(u002du002dglobal-palette7, #eeeeee);border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:var(--global-palette1, #3182CE);padding-top:0px;padding-right:0px;padding-bottom:10px;padding-left:0px;margin-bottom:10px;}.kt-info-box14181_ae7a89-85 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box14181_ae7a89-85 .kt-info-svg-icon-flip, .kt-info-box14181_ae7a89-85 .kt-blocks-info-box-number{font-size:20px;}.kt-info-box14181_ae7a89-85 .kt-blocks-info-box-media{color:var(--global-palette4, #2D3748);border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:3px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:7px;margin-bottom:0px;margin-left:0px;}.kt-info-box14181_ae7a89-85 .kt-infobox-textcontent h6.kt-blocks-info-box-title{color:var(--global-palette4, #2D3748);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box14181_ae7a89-85 .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette4, #2D3748);}.kt-info-box14181_ae7a89-85 .kt-blocks-info-box-learnmore{background:transparent;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}@media all and (max-width: 1024px){.kt-info-box14181_ae7a89-85 .kt-blocks-info-box-link-wrap{border-top:0px solid var(u002du002dglobal-palette7, #eeeeee);border-right:0px solid var(u002du002dglobal-palette7, #eeeeee);border-bottom:1px solid #979797;border-left:0px solid var(u002du002dglobal-palette7, #eeeeee);}}@media all and (max-width: 767px){.kt-info-box14181_ae7a89-85 .kt-blocks-info-box-link-wrap{border-top:0px solid var(u002du002dglobal-palette7, #eeeeee);border-right:0px solid var(u002du002dglobal-palette7, #eeeeee);border-bottom:1px solid #979797;border-left:0px solid var(u002du002dglobal-palette7, #eeeeee);}}<\/style> <div class=\"wp-block-kadence-infobox kt-info-box14181_ae7a89-85 info_block_01\">     <span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-left kt-info-halign-left kb-info-box-vertical-media-align-top\">         <div class=\"kt-blocks-info-box-media-container\">             <div class=\"kt-blocks-info-box-media kt-info-media-animate-none\">                 <div class=\"kadence-info-box-icon-container kt-info-icon-animate-none\">                     <div class=\"kadence-info-box-icon-inner-container\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_book kt-info-svg-icon\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  role=\"img\"><title>Hora<\/title><path d=\"M4 19.5A2.5 2.5 0 0 1 6.5 17H20\"\/><path d=\"M6.5 2H20v20H6.5A2.5 2.5 0 0 1 4 19.5v-15A2.5 2.5 0 0 1 6.5 2z\"\/><\/svg><\/span><\/div>                 <\/div>             <\/div>         <\/div>         <div class=\"kt-infobox-textcontent\">             <h6 class=\"kt-blocks-info-box-title\">Tipo de publicaci\u00f3n<\/h6><p class=\"kt-blocks-info-box-text\"><a href=\"\/publicacions\/resumen-de-actividades\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Resumen de actividades<\/a><\/p>        <\/div>     <\/span> <\/div>                  <style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box15198_70ed2d-ec .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box15198_70ed2d-ec .kt-blocks-info-box-link-wrap{border-top:0px solid var(u002du002dglobal-palette7, #eeeeee);border-right:0px solid var(u002du002dglobal-palette7, #eeeeee);border-bottom:0px solid #979797;border-left:0px solid var(u002du002dglobal-palette7, #eeeeee);border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:var(--global-palette1, #3182CE);padding-top:0px;padding-right:0px;padding-bottom:10px;padding-left:0px;}.kt-info-box15198_70ed2d-ec .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box15198_70ed2d-ec .kt-info-svg-icon-flip, .kt-info-box15198_70ed2d-ec .kt-blocks-info-box-number{font-size:20px;}.kt-info-box15198_70ed2d-ec .kt-blocks-info-box-media{color:var(--global-palette4, #2D3748);border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:3px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:7px;margin-bottom:0px;margin-left:0px;}.kt-info-box15198_70ed2d-ec .kt-infobox-textcontent h6.kt-blocks-info-box-title{color:var(--global-palette4, #2D3748);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box15198_70ed2d-ec .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette4, #2D3748);}.kt-info-box15198_70ed2d-ec .kt-blocks-info-box-learnmore{background:transparent;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}@media all and (max-width: 1024px){.kt-info-box15198_70ed2d-ec .kt-blocks-info-box-link-wrap{border-top:0px solid var(u002du002dglobal-palette7, #eeeeee);border-right:0px solid var(u002du002dglobal-palette7, #eeeeee);border-bottom:0px solid #979797;border-left:0px solid var(u002du002dglobal-palette7, #eeeeee);}}@media all and (max-width: 767px){.kt-info-box15198_70ed2d-ec .kt-blocks-info-box-link-wrap{border-top:0px solid var(u002du002dglobal-palette7, #eeeeee);border-right:0px solid var(u002du002dglobal-palette7, #eeeeee);border-bottom:0px solid #979797;border-left:0px solid var(u002du002dglobal-palette7, #eeeeee);}}<\/style> <div class=\"wp-block-kadence-infobox kt-info-box15198_70ed2d-ec info_block_01\">     <span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-left kt-info-halign-left kb-info-box-vertical-media-align-top\">         <div class=\"kt-blocks-info-box-media-container\">             <div class=\"kt-blocks-info-box-media kt-info-media-animate-none\">                 <div class=\"kadence-info-box-icon-container kt-info-icon-animate-none\">                     <div class=\"kadence-info-box-icon-inner-container\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_calendar kt-info-svg-icon\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  role=\"img\"><title>Hora<\/title><rect x=\"3\" y=\"4\" width=\"18\" height=\"18\" rx=\"2\" ry=\"2\"\/><line x1=\"16\" y1=\"2\" x2=\"16\" y2=\"6\"\/><line x1=\"8\" y1=\"2\" x2=\"8\" y2=\"6\"\/><line x1=\"3\" y1=\"10\" x2=\"21\" y2=\"10\"\/><\/svg><\/span><\/div>                 <\/div>             <\/div>         <\/div>         <div class=\"kt-infobox-textcontent\">             <h6 class=\"kt-blocks-info-box-title\">Data<\/h6>             <p class=\"kt-blocks-info-box-text\">24-11-2006<\/p>         <\/div>     <\/span> <\/div>              <\/div>                      <\/div>                    <\/div><\/div>          <style>.kb-row-layout-id15198_57c2d8-c9 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id15198_57c2d8-c9 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id15198_57c2d8-c9 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, calc(70% - ((var(--global-kb-gap-md, 2rem) * 1 )\/2)))minmax(0, calc(30% - ((var(--global-kb-gap-md, 2rem) * 1 )\/2)));}.kb-row-layout-id15198_57c2d8-c9 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id15198_57c2d8-c9 > .kt-row-column-wrap{grid-template-columns:minmax(0, 2fr) minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id15198_57c2d8-c9 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id15198_57c2d8-c9 alignnone content_article_agenda wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-left-golden kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">         <style>.kadence-column15198_459565-82 > .kt-inside-inner-col,.kadence-column15198_459565-82 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column15198_459565-82 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column15198_459565-82 > .kt-inside-inner-col{flex-direction:column;}.kadence-column15198_459565-82 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column15198_459565-82 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column15198_459565-82{position:relative;}@media all and (max-width: 1024px){.kadence-column15198_459565-82 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column15198_459565-82 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>         <div class=\"wp-block-kadence-column kadence-column15198_459565-82\">             <div class=\"kt-inside-inner-col\">             <div class=\"autor_post wp-block-post-author-name\"><a href=\"https:\/\/www.amicsdelpais.com\/es\/author\/sebap\/\" target=\"_blank\" class=\"wp-block-post-author-name__link\">SEBAP<\/a><\/div>             <div class=\"summary_post wp-block-post-excerpt\"><p class=\"wp-block-post-excerpt__excerpt\">En nuestra convocatoria mensual del pasado 24 de octubre, contamos con la presencia de Isabel Aguilera, Directora General de Google, como ponente invitada. Su intervenci\u00f3 resalt\u00f3 por su formato novedoso, desenfadado y caracter\u00edstico de la cultura y filosof\u00eda de Google. <\/p><\/div>                                                                    <style>.kb-row-layout-id22850_b19245-db > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id22850_b19245-db > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id22850_b19245-db > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:24px;padding-bottom:0px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id22850_b19245-db{background-color:#fecc8c;background-image:url('https:\/\/www.amicsdelpais.com\/wp-content\/uploads\/2025\/06\/bg_newsletter_01.svg');background-size:auto;background-position:100% 0%;background-attachment:scroll;background-repeat:repeat-y;}.kb-row-layout-id22850_b19245-db > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id22850_b19245-db > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id22850_b19245-db > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id22850_b19245-db alignnone kt-row-has-bg block_newsletter wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column22850_a01aca-24 > .kt-inside-inner-col{padding-bottom:0px;}.kadence-column22850_a01aca-24 > .kt-inside-inner-col,.kadence-column22850_a01aca-24 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column22850_a01aca-24 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column22850_a01aca-24 > .kt-inside-inner-col{flex-direction:column;}.kadence-column22850_a01aca-24 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column22850_a01aca-24 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column22850_a01aca-24{position:relative;}@media all and (max-width: 1024px){.kadence-column22850_a01aca-24 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column22850_a01aca-24 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column22850_a01aca-24\"><div class=\"kt-inside-inner-col\">\n<h2 class=\"wp-block-heading\">Suscr\u00edbete al newsletter<\/h2>\n\n\n\n<p>Suscr\u00edbete al <strong>Newsletter de Amics del Pa\u00eds<\/strong> para estar al d\u00eda de todo lo que hacemos. Recibir\u00e1s informaci\u00f3n sobre nuestras actividades, noticias destacadas y las convocatorias y novedades de las conferencias que organizamos.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f42828-o1\" lang=\"es-ES\" dir=\"ltr\" data-wpcf7-id=\"42828\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/es\/wp-json\/wp\/v2\/posts\/21699#wpcf7-f42828-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Formulario de contacto\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"42828\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.5\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"es_ES\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f42828-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<p>\t\t<div id=\"cf7md-form\" class=\"cf7md-form cf7md-spacing--tight\">\n\t\t\t<div class=\"mdc-layout-grid\">\n\t\t\t\t\t\t\t\t\n<\/p>\n<p>\t\t<div class=\"cf7md-item cf7md-text mdc-layout-grid__cell mdc-layout-grid__cell--span-12 mdc-layout-grid__cell--span-6-desktop mdc-layout-grid__cell--span-4-tablet mdc-layout-grid__cell--span-4-mobile\">\n\t\t\t<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"nom\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Nombre\" value=\"\" type=\"text\" name=\"nom\" \/><\/span><br \/>\n\t\t\t\t\t\t<div style=\"display: none;\" class=\"cf7md-text-html\">\n\t\t\t\t<div class=\"mdc-textfield\" data-mdc-auto-init=\"MDCTextfield\">\n\t\t\t\t\t<label class=\"mdc-textfield__label\"><\/label>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<br \/>\n\t\t<div class=\"cf7md-item cf7md-text mdc-layout-grid__cell mdc-layout-grid__cell--span-12 mdc-layout-grid__cell--span-6-desktop mdc-layout-grid__cell--span-4-tablet mdc-layout-grid__cell--span-4-mobile\">\n\t\t\t<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"cognoms\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Apellidos\" value=\"\" type=\"text\" name=\"cognoms\" \/><\/span><br \/>\n\t\t\t\t\t\t<div style=\"display: none;\" class=\"cf7md-text-html\">\n\t\t\t\t<div class=\"mdc-textfield\" data-mdc-auto-init=\"MDCTextfield\">\n\t\t\t\t\t<label class=\"mdc-textfield__label\"><\/label>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\n<\/p>\n<p>\t\t<div class=\"cf7md-item cf7md-text mdc-layout-grid__cell mdc-layout-grid__cell--span-12 mdc-layout-grid__cell--span-6-desktop mdc-layout-grid__cell--span-4-tablet mdc-layout-grid__cell--span-4-mobile\">\n\t\t\t<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Correo electr\u00f3nico\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span><br \/>\n\t\t\t\t\t\t<div style=\"display: none;\" class=\"cf7md-text-html\">\n\t\t\t\t<div class=\"mdc-textfield\" data-mdc-auto-init=\"MDCTextfield\">\n\t\t\t\t\t<label class=\"mdc-textfield__label\"><\/label>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<br \/>\n\t\t<div class=\"cf7md-item cf7md-text mdc-layout-grid__cell mdc-layout-grid__cell--span-12 mdc-layout-grid__cell--span-6-desktop mdc-layout-grid__cell--span-4-tablet mdc-layout-grid__cell--span-4-mobile\">\n\t\t\t<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"telefon\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-tel\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Tel\u00e9fono\" value=\"\" type=\"tel\" name=\"telefon\" \/><\/span><br \/>\n\t\t\t\t\t\t<div style=\"display: none;\" class=\"cf7md-text-html\">\n\t\t\t\t<div class=\"mdc-textfield\" data-mdc-auto-init=\"MDCTextfield\">\n\t\t\t\t\t<label class=\"mdc-textfield__label\"><\/label>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\n<\/p>\n<p>\t\t<div class=\"cf7md-item cf7md-text mdc-layout-grid__cell mdc-layout-grid__cell--span-12 mdc-layout-grid__cell--span-6-desktop mdc-layout-grid__cell--span-4-tablet mdc-layout-grid__cell--span-4-mobile\">\n\t\t\t<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"entitat\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" placeholder=\"Entidad \/ Empresa\" value=\"\" type=\"text\" name=\"entitat\" \/><\/span><br \/>\n\t\t\t\t\t\t<div style=\"display: none;\" class=\"cf7md-text-html\">\n\t\t\t\t<div class=\"mdc-textfield\" data-mdc-auto-init=\"MDCTextfield\">\n\t\t\t\t\t<label class=\"mdc-textfield__label\"><\/label>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<br \/>\n\t\t<div class=\"cf7md-item cf7md-text mdc-layout-grid__cell mdc-layout-grid__cell--span-12 mdc-layout-grid__cell--span-6-desktop mdc-layout-grid__cell--span-4-tablet mdc-layout-grid__cell--span-4-mobile\">\n\t\t\t<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"cargo\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" placeholder=\"Cargo\" value=\"\" type=\"text\" name=\"cargo\" \/><\/span><br \/>\n\t\t\t\t\t\t<div style=\"display: none;\" class=\"cf7md-text-html\">\n\t\t\t\t<div class=\"mdc-textfield\" data-mdc-auto-init=\"MDCTextfield\">\n\t\t\t\t\t<label class=\"mdc-textfield__label\"><\/label>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\n<\/p>\n<p>\t\t<div class=\"cf7md-item cf7md-accept cf7md-is-wpcf7v5 mdc-layout-grid__cell mdc-layout-grid__cell--span-12 mdc-layout-grid__cell--span-12-desktop mdc-layout-grid__cell--span-8-tablet mdc-layout-grid__cell--span-4-mobile\">\n\t\t\t\t\t\t<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"acceptance-273\"><span class=\"wpcf7-form-control wpcf7-acceptance\"><span class=\"wpcf7-list-item\"><label><input type=\"checkbox\" name=\"acceptance-273\" value=\"1\" aria-invalid=\"false\" \/><span class=\"wpcf7-list-item-label\">He le\u00eddo y acepto la <a href=\"https:\/\/www.amicsdelpais.com\/es\/avis-legal\" title=\"Tratamiento de los Datos de Car\u00e1cter Personal\" target=\"_blank\">pol\u00edtica de privacidad (GDPR)<\/a>.<\/span><\/label><\/span><\/span><\/span><br \/>\n\t\t\t<label class=\"cf7md-accept-label\"><\/label>\n\t\t\t<div style=\"display: none;\" class=\"cf7md-checkbox-html\">\n\t\t\t\t<div class=\"mdc-checkbox__background\">\n\t\t\t\t\t<svg version=\"1.1\"\n\t\t\t\t\t\tclass=\"mdc-checkbox__checkmark\"\n\t\t\t\t\t\txmlns=\"http:\/\/www.w3.org\/2000\/svg\"\n\t\t\t\t\t\tviewBox=\"0 0 24 24\"\n\t\t\t\t\t\txml:space=\"preserve\">\n\t\t\t\t\t\t<path class=\"mdc-checkbox__checkmark__path\"\n\t\t\t\t\t\t\tfill=\"none\"\n\t\t\t\t\t\t\tstroke=\"white\"\n\t\t\t\t\t\t\td=\"M1.73,12.91 8.1,19.28 22.79,4.59\"\/>\n\t\t\t\t\t<\/svg>\n\t\t\t\t\t<div class=\"mdc-checkbox__mixedmark\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<br \/>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"\" type=\"hidden\" name=\"origen\" \/><br \/>\n\t\t<div class=\"cf7md-item cf7md-submit mdc-layout-grid__cell mdc-layout-grid__cell--span-12 mdc-layout-grid__cell--span-12-desktop mdc-layout-grid__cell--span-8-tablet mdc-layout-grid__cell--span-4-mobile\">\n\t\t\t<br \/>\n<input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Subscribirme\" \/><br \/>\n\t\t\t<svg class=\"cf7md-spinner\" width=\"25px\" height=\"25px\" viewBox=\"0 0 66 66\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n\t\t\t\t<circle class=\"cf7md-spinner-path\" fill=\"none\" stroke-width=\"6\" stroke-linecap=\"round\" cx=\"33\" cy=\"33\" r=\"30\"><\/circle>\n\t\t\t<\/svg>\n\t\t<\/div>\n\t\t<br \/>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n\n<\/div><\/div>\n\n<\/div><\/div>             <\/div>         <\/div>                   <style>.kadence-column15198_b55ca3-7f > .kt-inside-inner-col,.kadence-column15198_b55ca3-7f > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column15198_b55ca3-7f > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column15198_b55ca3-7f > .kt-inside-inner-col{flex-direction:column;}.kadence-column15198_b55ca3-7f > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column15198_b55ca3-7f > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column15198_b55ca3-7f{position:relative;}@media all and (max-width: 1024px){.kadence-column15198_b55ca3-7f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column15198_b55ca3-7f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>         <div class=\"wp-block-kadence-column kadence-column15198_b55ca3-7f\">             <div class=\"kt-inside-inner-col\">                                               <\/div>         <\/div>                  <\/div><\/div>                   <p><\/p>         ","protected":false},"excerpt":{"rendered":"<p>En nuestra convocatoria mensual del pasado 24 de octubre, contamos con la presencia de Isabel Aguilera, Directora General de Google, como ponente invitada. Su intervenci\u00f3 resalt\u00f3 por su formato novedoso, desenfadado y caracter\u00edstico de la cultura y filosof\u00eda de Google.<\/p>\n","protected":false},"author":103,"featured_media":17110,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"categories":[210,732,735,193,200],"tags":[],"class_list":["post-21699","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-res-barcelona-tribuna-es","category-cercle-per-al-coneixement-publicaciones","category-circulo-para-el-conocimiento-publicaciones","category-publicaciones","category-resumen-de-actividades"],"taxonomy_info":{"category":[{"value":210,"label":"Barcelona Tribuna resum"},{"value":732,"label":"Cercle per al Coneixement Publicaciones"},{"value":735,"label":"C\u00edrculo para el Conocimiento Publicaciones"},{"value":193,"label":"Publicaciones"},{"value":200,"label":"Resumen de actividades"}]},"featured_image_src_large":["https:\/\/www.amicsdelpais.com\/wp-content\/uploads\/2025\/07\/art_176_2g2c.jpg",235,271,false],"author_info":{"display_name":"SEBAP","author_link":"https:\/\/www.amicsdelpais.com\/es\/author\/sebap\/"},"comment_info":0,"category_info":[{"term_id":210,"name":"Barcelona Tribuna resum","slug":"res-barcelona-tribuna-es","term_group":0,"term_taxonomy_id":210,"taxonomy":"category","description":"","parent":200,"count":256,"filter":"raw","cat_ID":210,"category_count":256,"category_description":"","cat_name":"Barcelona Tribuna resum","category_nicename":"res-barcelona-tribuna-es","category_parent":200},{"term_id":732,"name":"Cercle per al Coneixement Publicaciones","slug":"cercle-per-al-coneixement-publicaciones","term_group":0,"term_taxonomy_id":732,"taxonomy":"category","description":"","parent":193,"count":1138,"filter":"raw","cat_ID":732,"category_count":1138,"category_description":"","cat_name":"Cercle per al Coneixement Publicaciones","category_nicename":"cercle-per-al-coneixement-publicaciones","category_parent":193},{"term_id":735,"name":"C\u00edrculo para el Conocimiento Publicaciones","slug":"circulo-para-el-conocimiento-publicaciones","term_group":0,"term_taxonomy_id":735,"taxonomy":"category","description":"","parent":771,"count":602,"filter":"raw","cat_ID":735,"category_count":602,"category_description":"","cat_name":"C\u00edrculo para el Conocimiento Publicaciones","category_nicename":"circulo-para-el-conocimiento-publicaciones","category_parent":771},{"term_id":193,"name":"Publicaciones","slug":"publicaciones","term_group":0,"term_taxonomy_id":193,"taxonomy":"category","description":"","parent":0,"count":761,"filter":"raw","cat_ID":193,"category_count":761,"category_description":"","cat_name":"Publicaciones","category_nicename":"publicaciones","category_parent":0},{"term_id":200,"name":"Resumen de actividades","slug":"resumen-de-actividades","term_group":0,"term_taxonomy_id":200,"taxonomy":"category","description":"","parent":193,"count":288,"filter":"raw","cat_ID":200,"category_count":288,"category_description":"","cat_name":"Resumen de actividades","category_nicename":"resumen-de-actividades","category_parent":193}],"tag_info":false,"_links":{"self":[{"href":"https:\/\/www.amicsdelpais.com\/es\/wp-json\/wp\/v2\/posts\/21699","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.amicsdelpais.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.amicsdelpais.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.amicsdelpais.com\/es\/wp-json\/wp\/v2\/users\/103"}],"replies":[{"embeddable":true,"href":"https:\/\/www.amicsdelpais.com\/es\/wp-json\/wp\/v2\/comments?post=21699"}],"version-history":[{"count":0,"href":"https:\/\/www.amicsdelpais.com\/es\/wp-json\/wp\/v2\/posts\/21699\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.amicsdelpais.com\/es\/wp-json\/wp\/v2\/media\/17110"}],"wp:attachment":[{"href":"https:\/\/www.amicsdelpais.com\/es\/wp-json\/wp\/v2\/media?parent=21699"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.amicsdelpais.com\/es\/wp-json\/wp\/v2\/categories?post=21699"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.amicsdelpais.com\/es\/wp-json\/wp\/v2\/tags?post=21699"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}